{"id":8751,"date":"2022-03-24T16:41:41","date_gmt":"2022-03-24T16:41:41","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=8751"},"modified":"2022-11-30T01:17:50","modified_gmt":"2022-11-30T01:17:50","slug":"le-sac-d-anvers-connu-comme-la-furie-espagnole","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/le-sac-d-anvers-connu-comme-la-furie-espagnole\/","title":{"rendered":"Le sac d&#8217;Anvers, connu comme la Furie Espagnole"},"content":{"rendered":"<p style=\"text-align: center;\"><label style=\"font-size: 15px;\">La fureur espagnole, auteur anonyme, vers 1585<\/label><\/p>\n<p>Le sac d&#8217;Anvers, souvent connu sous le nom de fureur espagnole \u00e0 Anvers, \u00e9tait un \u00e9pisode de la guerre de quatre-vingts ans. Au cours de cet \u00e9pisode sont morts plusieurs milliers d&#8217;habitants, c&#8217;est le plus grand massacre de l&#8217;histoire belge.<\/p>\n<figure id=\"attachment_8754\" aria-describedby=\"caption-attachment-8754\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/8751\/Philippe-II-par-Sofonisba-Anguissola.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-8754\" style=\"width: 100%; max-width: 360px; height: auto;\" title=\"Philippe II par Sofonisba Anguissola, 1565 (Mus\u00e9e du Prado)\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/8751\/Philippe-II-par-Sofonisba-Anguissola-244x300.jpg\" alt=\"Philippe II par Sofonisba Anguissola, 1565 (Mus\u00e9e du Prado)\" width=\"360\" height=\"443\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/8751\/Philippe-II-par-Sofonisba-Anguissola-244x300.jpg 244w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/8751\/Philippe-II-par-Sofonisba-Anguissola-832x1024.jpg 832w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/8751\/Philippe-II-par-Sofonisba-Anguissola-768x945.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/8751\/Philippe-II-par-Sofonisba-Anguissola-1248x1536.jpg 1248w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/8751\/Philippe-II-par-Sofonisba-Anguissola-1664x2048.jpg 1664w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/8751\/Philippe-II-par-Sofonisba-Anguissola-300x369.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/8751\/Philippe-II-par-Sofonisba-Anguissola-1300x1600.jpg 1300w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-8754\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Philippe II par Sofonisba Anguissola, 1565 (Mus\u00e9e du Prado).<\/label><\/figcaption><\/figure>\n<p>Entre le 4 novembre et le 7 novembre 1576, des tercios espagnols mutin\u00e9s de l&#8217;arm\u00e9e des Flandres commenc\u00e8rent le sac d&#8217;Anvers, entra\u00eenant trois jours d&#8217;horreur parmi la population de la ville, qui \u00e9tait le centre culturel, \u00e9conomique et financier des \u00ab Dix-Sept Provinces \u00bb. La sauvagerie du sac amena les provinces des Pays-Bas espagnols \u00e0 s&#8217;unir contre la couronne espagnole. La d\u00e9vastation a \u00e9galement caus\u00e9 le d\u00e9clin d&#8217;Anvers en tant que premi\u00e8re ville de la r\u00e9gion et a ouvert la voie \u00e0 l&#8217;essor d&#8217;Amsterdam.<\/p>\n<p>La principale cause du sac \u00e9tait le retard de paiement d\u00fb aux soldats par Philippe II. L&#8217;Espagne vient de d\u00e9clarer faillite. Les banquiers refusent d&#8217;effectuer les transactions que leur demande le roi d&#8217;Espagne tant qu&#8217;ils n&#8217;ont pas trouv\u00e9 de compromis. A titre d&#8217;exemple, le transfert depuis l&#8217;Espagne du salaire des troupes ne pouvait \u00eatre effectu\u00e9 par lettre de change (l&#8217;\u00e9quivalent au XVIe si\u00e8cle d&#8217;un mandat postal). Le gouvernement espagnol a donc d\u00fb transf\u00e9rer l&#8217;argent r\u00e9el par voie maritime &#8211; une op\u00e9ration beaucoup plus co\u00fbteuse, lente et p\u00e9rilleuse. Malheureusement pour Philippe, 400 000 florins destin\u00e9s \u00e0 payer les troupes ont \u00e9t\u00e9 saisis par le gouvernement d&#8217;Elizabeth I lorsque des navires contenant les florins se sont mis \u00e0 l&#8217;abri d&#8217;une temp\u00eate dans les ports anglais.<\/p>\n<p>Les soldats espagnols, furieux de combattre sans repos ni solde contre les rebelles, avaient d\u00e9j\u00e0 saccag\u00e9 Zierikzee et Alost, provoquant la r\u00e9union des quinze provinces loyales (la Hollande et la Z\u00e9lande \u00e9taient aux mains des rebelles) en \u00c9tats g\u00e9n\u00e9raux dans le but de retirer les mercenaires des Pays-Bas. C&#8217;\u00e9tait une proc\u00e9dure courante chez les soldats \u00e0 cette \u00e9poque, et leur proc\u00e9dure \u00e9tait invariable. Sans rompre leur c\u00e9l\u00e8bre discipline, ils choisiraient un nouveau chef, ou Eletto, parmi eux, et marcheraient en parfait ordre sous lui vers n&#8217;importe quelle cible. Dans ce cas, les soldats espagnols ont d\u00e9cid\u00e9 de trouver eux-m\u00eames leur solde tardive en pillant Anvers.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre le 4 novembre et le 7 novembre 1576, des tercios espagnols mutin\u00e9s de l&#8217;arm\u00e9e des Flandres commenc\u00e8rent le sac d&#8217;Anvers, entra\u00eenant trois jours d&#8217;horreur parmi la<\/p>\n","protected":false},"author":1,"featured_media":8752,"template":"","categoria_ficha":[1760],"class_list":["post-8751","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-d-anvers"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/8751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":6,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/8751\/revisions"}],"predecessor-version":[{"id":26633,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/8751\/revisions\/26633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/8752"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=8751"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=8751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}