{"id":7945,"date":"2022-03-16T13:18:58","date_gmt":"2022-03-16T13:18:58","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=7945"},"modified":"2023-09-26T20:51:34","modified_gmt":"2023-09-26T20:51:34","slug":"carte-de-lausanne","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-de-lausanne\/","title":{"rendered":"Carte de Lausanne"},"content":{"rendered":"<p>Carte de Lausanne, la capitale et la plus grande ville du canton suisse de Vaud. C&#8217;est une ville vallonn\u00e9e, situ\u00e9e sur les rives du lac L\u00e9man, \u00e0 mi-chemin entre les montagnes du Jura et les Alpes, et face \u00e0 la ville fran\u00e7aise d&#8217;\u00c9vian-les-Bains de l&#8217;autre c\u00f4t\u00e9 du lac. Lausanne est situ\u00e9e \u00e0 62 kilom\u00e8tres au nord-est de Gen\u00e8ve, sa grande voisine la plus proche.<\/p>\n<figure id=\"attachment_44167\" aria-describedby=\"caption-attachment-44167\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-de-localisation-de-Lausanne.png\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-44167\" title=\"Carte de localisation de Lausanne.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-de-localisation-de-Lausanne-300x192.png\" alt=\"Carte de localisation de Lausanne.\" width=\"360\" height=\"231\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-de-localisation-de-Lausanne-300x192.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-de-localisation-de-Lausanne-1024x657.png 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-de-localisation-de-Lausanne-768x493.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-de-localisation-de-Lausanne-1536x985.png 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-de-localisation-de-Lausanne-2048x1314.png 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-de-localisation-de-Lausanne-1600x1026.png 1600w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-44167\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte de localisation de Lausanne.<\/label><\/figcaption><\/figure>\n<p>La commune de Lausanne compte environ 140 000 habitants, ce qui en fait la quatri\u00e8me plus grande ville de Suisse apr\u00e8s B\u00e2le, Gen\u00e8ve et Zurich, l&#8217;ensemble de l&#8217;agglom\u00e9ration comptant environ 420 000 habitants (en janvier 2019). La zone m\u00e9tropolitaine de Lausanne-Gen\u00e8ve (comprenant Vevey-Montreux, Yverdon-les-Bains, le Valais et les parties \u00e9trang\u00e8res), commun\u00e9ment appel\u00e9e Arc l\u00e9manique, comptait plus de 1,3 million d&#8217;habitants en 2017 et conna\u00eet la croissance la plus rapide de Suisse.<\/p>\n<p>D&#8217;abord \u00e9tablissement celtique et romain au bord du lac, Lausanne est devenue une ville au pied de Notre-Dame, cath\u00e9drale \u00e9difi\u00e9e au XII<sup>e<\/sup> si\u00e8cle. Au XX<sup>e<\/sup> si\u00e8cle, Lausanne devient un haut lieu du sport international, accueillant le Comit\u00e9 International Olympique (qui reconna\u00eet la ville comme \u00abCapitale Olympique\u00bb depuis 1994), le Tribunal Arbitral du Sport et quelque 55 associations sportives internationales. Elle se situe dans une r\u00e9gion viticole r\u00e9put\u00e9e. La ville dispose d&#8217;un syst\u00e8me de m\u00e9tro de 28 stations, ce qui en fait la plus petite ville au monde \u00e0 disposer d&#8217;un syst\u00e8me de transport en commun rapide. Lausanne a accueilli les Jeux olympiques de la jeunesse d&#8217;hiver de 2020.<\/p>\n<p><strong>G\u00e9ographie<\/strong><\/p>\n<figure id=\"attachment_44168\" aria-describedby=\"caption-attachment-44168\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Centre-ville-de-Lausanne.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-44168\" title=\"Centre-ville de Lausanne.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Centre-ville-de-Lausanne-300x285.jpg\" alt=\"Centre-ville de Lausanne.\" width=\"360\" height=\"342\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Centre-ville-de-Lausanne-300x285.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Centre-ville-de-Lausanne-1024x972.jpg 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Centre-ville-de-Lausanne-768x729.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Centre-ville-de-Lausanne-1536x1458.jpg 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Centre-ville-de-Lausanne.jpg 1546w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-44168\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Centre-ville de Lausanne.<\/label><\/figcaption><\/figure>\n<p>la ville de Lausanne\u00a0se situe sur la rive nord du lac L\u00e9man, \u00e0 mi-chemin entre les montagnes du Jura et les Alpes, en plein c\u0153ur de la Suisse romande, et face \u00e0 la ville fran\u00e7aise d&#8217;\u00c9vian-les-Bains de l&#8217;autre c\u00f4t\u00e9 du lac. Lausanne est situ\u00e9e \u00e0 62 kilom\u00e8tres au nord-est de Gen\u00e8ve, sa grande voisine la plus proche.<\/p>\n<p>L&#8217;\u00e9l\u00e9ment g\u00e9ographique le plus important de la r\u00e9gion lausannoise est le lac L\u00e9man. Lausanne est construite sur le versant sud du plateau suisse, avec un d\u00e9nivel\u00e9 d&#8217;environ 500 m\u00e8tres entre les rives du lac d&#8217;Ouchy et sa limite nord limitrophe du Mont-sur-Lausanne et d&#8217;\u00c9palinges. Lausanne offre un panorama spectaculaire sur le lac et les Alpes suisses et savoyardes.<\/p>\n<p>Outre son trac\u00e9 g\u00e9n\u00e9ralement orient\u00e9 vers le sud, le centre de la ville est le site d&#8217;une ancienne rivi\u00e8re, le Flon, recouverte depuis le XIX<sup>\u00e8me<\/sup> si\u00e8cle. L&#8217;ancienne rivi\u00e8re forme une gorge traversant le milieu de la ville au sud du vieux centre-ville, suivant g\u00e9n\u00e9ralement le cours de l&#8217;actuelle rue Centrale, avec plusieurs ponts traversant la d\u00e9pression pour relier les quartiers adjacents.<\/p>\n<figure id=\"attachment_44169\" aria-describedby=\"caption-attachment-44169\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-des-rues-de-la-ville-de-Lausanne.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-44169\" title=\"Carte des rues de la ville de Lausanne.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-des-rues-de-la-ville-de-Lausanne-211x300.jpg\" alt=\"Carte des rues de la ville de Lausanne.\" width=\"360\" height=\"513\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-des-rues-de-la-ville-de-Lausanne-211x300.jpg 211w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-des-rues-de-la-ville-de-Lausanne-719x1024.jpg 719w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-des-rues-de-la-ville-de-Lausanne-768x1094.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-des-rues-de-la-ville-de-Lausanne-1078x1536.jpg 1078w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-des-rues-de-la-ville-de-Lausanne-1437x2048.jpg 1437w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-des-rues-de-la-ville-de-Lausanne-300x427.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/7945\/Carte-des-rues-de-la-ville-de-Lausanne-1123x1600.jpg 1123w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-44169\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte des rues de la ville de Lausanne.<\/label><\/figcaption><\/figure>\n<p>En raison des diff\u00e9rences consid\u00e9rables d&#8217;altitude, les touristes doivent noter sur quel plan d&#8217;\u00e9l\u00e9vation ils se trouvent et o\u00f9 ils veulent aller, sinon ils se retrouveront \u00e0 des dizaines de m\u00e8tres en dessous ou au-dessus de la rue dans laquelle ils essaient d&#8217;aller. Le nom Flon est \u00e9galement utilis\u00e9 pour la station de m\u00e9tro situ\u00e9e dans les gorges.<\/p>\n<p>La commune comprend les villages de Vidy, Cour, Ouchy, Mornex, Chailly, La Sallaz, Vennes, Montblesson, Vers-chez-les-Blanc, Montheron et Chalet-\u00e0-Gobet (871 m) ainsi que l&#8217;enclave du Vernand.<\/p>\n<p>Lausanne est situ\u00e9e \u00e0 la limite entre les vastes r\u00e9gions viticoles du Lavaux (\u00e0 l&#8217;est) et de la C\u00f4te (\u00e0 l&#8217;ouest).<\/p>\n<p>Lausanne a une superficie, entre 2012 et 2014, de 41,38 \u00e0 41,37 kilom\u00e8tres carr\u00e9s (selon la m\u00e9thode de calcul). De cette superficie, 6,22 km\u00b2 ou 15,0 % sont utilis\u00e9s \u00e0 des fins agricoles, tandis que 16,06 km\u00b2 ou 38,8 % sont bois\u00e9s. Sur le reste du territoire, 19,00 km\u00b2 ou 45,9 % sont occup\u00e9s par des b\u00e2timents ou des routes, 0,08 km\u00b2 ou 0,2 % sont des rivi\u00e8res ou des lacs et 0,01 km\u00b2 ou 0,0 % sont des terres improductives.<\/p>\n<p>Parmi la zone b\u00e2tie, les b\u00e2timents industriels repr\u00e9sentaient 1,6 % de la superficie totale, tandis que les logements et les b\u00e2timents repr\u00e9sentaient 22,8 % et les infrastructures de transport 12,4 %. Les infrastructures \u00e9lectriques et hydrauliques ainsi que d&#8217;autres zones sp\u00e9cialement am\u00e9nag\u00e9es repr\u00e9sentaient 1,6 % de la superficie, tandis que les parcs, les ceintures vertes et les terrains de sport repr\u00e9sentaient 7,4 %. Hors des terres bois\u00e9es, toute la superficie bois\u00e9e est couverte de for\u00eats denses. Parmi les terres agricoles, 9,4 % sont utilis\u00e9es pour la culture et 4,9 % sont des p\u00e2turages. Toute l&#8217;eau de la commune se trouve dans les lacs et les ruisseaux.<\/p>\n<p>La commune faisait partie de l&#8217;ancien district de Lausanne jusqu&#8217;\u00e0 sa dissolution le 31 ao\u00fbt 2006 et elle est devenue le chef-lieu du nouveau district de Lausanne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carte de Lausanne, la capitale et la plus grande ville du canton suisse de Vaud. C&#8217;est une ville vallonn\u00e9e, situ\u00e9e sur les rives du lac L\u00e9man, \u00e0 mi-chemin entre les montagnes du Jura et les Alpes, et face \u00e0 la ville fran\u00e7aise d&#8217;\u00c9vian-les-Bains de l&#8217;autre c\u00f4t\u00e9 du lac. Lausanne est situ\u00e9e \u00e0 62 kilom\u00e8tres au [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11695,"template":"","categoria_ficha":[1745],"class_list":["post-7945","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-lausanne"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/7945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/7945\/revisions"}],"predecessor-version":[{"id":44170,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/7945\/revisions\/44170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/11695"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=7945"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=7945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}