{"id":773,"date":"2022-02-04T00:14:53","date_gmt":"2022-02-04T00:14:53","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=773"},"modified":"2024-04-16T18:40:13","modified_gmt":"2024-04-16T18:40:13","slug":"carte-du-danemark","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-du-danemark\/","title":{"rendered":"Carte du Danemark"},"content":{"rendered":"<p><strong>Carte du Danemark<\/strong>, un pays nordique d&#8217;Europe du Nord. Le Danemark europ\u00e9en, qui est le plus m\u00e9ridional des pays scandinaves, se compose d&#8217;une p\u00e9ninsule, le Jutland, et d&#8217;un archipel de 407 \u00eeles dont 79 habit\u00e9es (2009), les plus grandes \u00e9tant Seeland, Fionie et Vendsyssel-Thy. Les \u00eeles se caract\u00e9risent par des terres arables plates et des c\u00f4tes sablonneuses, une faible altitude et un climat temp\u00e9r\u00e9. Le Danemark se situe au sud-ouest de la Su\u00e8de et au sud de la Norv\u00e8ge, et est bord\u00e9 au sud par l&#8217;Allemagne. Le Royaume du Danemark est constitutionnellement un \u00c9tat unitaire comprenant le Danemark m\u00e9tropolitain et deux territoires autonomes dans l&#8217;oc\u00e9an Atlantique Nord: les <a href=\"https:\/\/gifex.com\/fr\/fichier\/carte-des-iles-feroe\/\" rel=\"noopener\" target=\"_blank\">\u00eeles F\u00e9ro\u00e9<\/a> et le Groenland. Le Danemark a une superficie totale de 42,943 km\u00b2 et la superficie totale, y compris le Groenland et les \u00eeles F\u00e9ro\u00e9, est de 2,220,930 km\u00b2. Le Danemark m\u00e9tropolitain a une population de 5,850,189 (en 2021), dont 800 000 vivent dans la capitale et plus grande ville de Copenhague.<\/p>\n<figure id=\"attachment_44921\" aria-describedby=\"caption-attachment-44921\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/44919\/Carte-de-Copenhague.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-44921\" title=\"Carte de Copenhague\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/44919\/Carte-de-Copenhague-300x249.jpg\" alt=\"Carte de Copenhague\" width=\"360\" height=\"299\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/44919\/Carte-de-Copenhague-300x249.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/44919\/Carte-de-Copenhague-1024x850.jpg 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/44919\/Carte-de-Copenhague-768x638.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/44919\/Carte-de-Copenhague-1536x1275.jpg 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/44919\/Carte-de-Copenhague-2048x1700.jpg 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/44919\/Carte-de-Copenhague-1600x1328.jpg 1600w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-44921\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte de Copenhague, capitale et la plus grande ville du Danemark.<\/label><\/figcaption><\/figure>\n<ul>\n<li>Superficie totale du Danemark 2,220,930 km\u00b2<\/li>\n<li>En 2021 la population du Danemark \u00e9tait de 5,850,189<\/li>\n<li>La capitale et plus grande ville du pays est Copenhague<\/li>\n<\/ul>\n<p>Le royaume unifi\u00e9 du Danemark a \u00e9merg\u00e9 au 8\u00e8me si\u00e8cle en tant que nation de marins comp\u00e9tents dans la lutte pour le contr\u00f4le de la mer Baltique. Le Danemark, la Su\u00e8de et la Norv\u00e8ge \u00e9taient dirig\u00e9s ensemble sous un seul souverain dans l&#8217;Union de Kalmar, \u00e9tablie en 1397 et se terminant par la s\u00e9cession su\u00e9doise en 1523. Les r\u00e9gions du Danemark et de la Norv\u00e8ge sont rest\u00e9s ensemble sous le m\u00eame monarque jusqu&#8217;en 1814, dans l&#8217;union dano-norv\u00e9gien. \u00c0 partir du 17<sup>e<\/sup> si\u00e8cle, il y a eu plusieurs guerres d\u00e9vastatrices avec l&#8217;empire su\u00e9dois, se terminant par d&#8217;importantes cessions de territoire \u00e0 la Su\u00e8de. Apr\u00e8s les guerres napol\u00e9oniennes, la Norv\u00e8ge a \u00e9t\u00e9 c\u00e9d\u00e9e \u00e0 la Su\u00e8de, tandis que le Danemark a conserv\u00e9 les \u00eeles F\u00e9ro\u00e9, le Groenland et l&#8217;Islande. Au 19<sup>e<\/sup> si\u00e8cle, il y a eu une vague de mouvements nationalistes, qui ont \u00e9t\u00e9 vaincus lors de la premi\u00e8re guerre du Schleswig. Apr\u00e8s la deuxi\u00e8me guerre du Schleswig en 1864, le Danemark a perdu le duch\u00e9 de Schleswig au profit de la Prusse. Le Danemark est rest\u00e9 neutre pendant la Premi\u00e8re Guerre mondiale; cependant, en 1920, la moiti\u00e9 nord du Schleswig redevint danoise. En avril 1940, une invasion allemande a vu de br\u00e8ves escarmouches militaires tandis que le mouvement de r\u00e9sistance danois \u00e9tait actif de 1943 jusqu&#8217;\u00e0 la capitulation allemande en mai 1945. Exportateur industrialis\u00e9 de produits agricoles dans la seconde moiti\u00e9 du XIX<sup>e<\/sup> si\u00e8cle, le Danemark a introduit d&#8217;importantes r\u00e9formes r\u00e9formes sociales et du march\u00e9 du travail au d\u00e9but du 20e si\u00e8cle qui ont jet\u00e9 les bases du mod\u00e8le actuel d&#8217;\u00c9tat-providence avec une \u00e9conomie mixte tr\u00e8s d\u00e9velopp\u00e9e.<\/p>\n<figure id=\"attachment_44863\" aria-describedby=\"caption-attachment-44863\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/773\/Le-Danemark-le-15-mars-2002-depuis-l-espace.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-44863\" title=\"Le Danemark le 15 mars 2002 depuis l'espace.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/773\/Le-Danemark-le-15-mars-2002-depuis-l-espace-300x245.jpg\" alt=\"Le Danemark le 15 mars 2002 depuis l'espace.\" width=\"360\" height=\"294\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/773\/Le-Danemark-le-15-mars-2002-depuis-l-espace-300x245.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/773\/Le-Danemark-le-15-mars-2002-depuis-l-espace-1024x835.jpg 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/773\/Le-Danemark-le-15-mars-2002-depuis-l-espace-768x626.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/773\/Le-Danemark-le-15-mars-2002-depuis-l-espace-1536x1252.jpg 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/773\/Le-Danemark-le-15-mars-2002-depuis-l-espace-2048x1670.jpg 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/773\/Le-Danemark-le-15-mars-2002-depuis-l-espace-1600x1305.jpg 1600w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-44863\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Le Danemark le 15 mars 2002 depuis l&#8217;espace.<\/label><\/figcaption><\/figure>\n<p>La Constitution du Danemark a \u00e9t\u00e9 sign\u00e9e le 5 juin 1849, mettant fin \u00e0 la monarchie absolue, qui avait commenc\u00e9 en 1660. Elle \u00e9tablit une monarchie constitutionnelle organis\u00e9e comme une d\u00e9mocratie parlementaire. Le gouvernement et le parlement national si\u00e8gent \u00e0 Copenhague, la capitale du pays, la plus grande ville et le principal centre commercial. Le Danemark exerce une influence h\u00e9g\u00e9monique dans le royaume danois, d\u00e9l\u00e9guant des pouvoirs pour g\u00e9rer les affaires int\u00e9rieures. L&#8217;autonomie a \u00e9t\u00e9 \u00e9tablie dans les \u00eeles F\u00e9ro\u00e9 en 1948; au Groenland, l&#8217;autonomie a \u00e9t\u00e9 instaur\u00e9e en 1979 et encore plus d&#8217;autonomie en 2009. Le Danemark fait partie de l&#8217;Union europ\u00e9enne, bien qu&#8217;il n&#8217;utilise pas l&#8217;euro; il conserve sa propre monnaie, la couronne. Lorsque le pays a rejoint la CEE en 1973, il l&#8217;a fait sans les \u00eeles F\u00e9ro\u00e9, tandis que le Groenland a choisi de faire s\u00e9cession de la CEE en 1985.<\/p>\n<p>Pays d\u00e9velopp\u00e9, les Danois b\u00e9n\u00e9ficient d&#8217;un niveau de vie \u00e9lev\u00e9 et le pays se classe tr\u00e8s bien dans certains indicateurs de performance nationale, notamment l&#8217;\u00e9ducation, les soins de sant\u00e9, la protection des libert\u00e9s civiles, la gouvernance d\u00e9mocratique et l&#8217;\u00e9galit\u00e9 des LGBT. Il fait partie des membres fondateurs de l&#8217;OTAN, du Conseil nordique, de l&#8217;OCDE, de l&#8217;Organisation pour la s\u00e9curit\u00e9 et la coop\u00e9ration en Europe (OSCE) et des Nations Unies; il fait \u00e9galement partie de l&#8217;espace Schengen. Le Danemark a \u00e9galement des liens \u00e9troits avec ses voisins scandinaves sur le plan linguistique, la langue danoise \u00e9tant partiellement intelligible avec le norv\u00e9gien et le su\u00e9dois.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carte du Danemark, un pays nordique d&#8217;Europe du Nord. Le Danemark europ\u00e9en, qui est le plus m\u00e9ridional des pays scandinaves, se compose d&#8217;une p\u00e9ninsule, le Jutland<\/p>\n","protected":false},"author":1,"featured_media":44864,"template":"","categoria_ficha":[108],"class_list":["post-773","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-du-danemark"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/773\/revisions"}],"predecessor-version":[{"id":46133,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/773\/revisions\/46133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/44864"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=773"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}