{"id":54954,"date":"2024-11-28T18:01:13","date_gmt":"2024-11-28T18:01:13","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=54954"},"modified":"2024-11-28T18:01:13","modified_gmt":"2024-11-28T18:01:13","slug":"carte-climatique-de-la-nouvelle-zelande","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-climatique-de-la-nouvelle-zelande\/","title":{"rendered":"Carte climatique de la Nouvelle-Z\u00e9lande"},"content":{"rendered":"<p style=\"text-align: center;\"><label style=\"font-size: 15px;\">Carte de classification climatique de K\u00f6ppen\u2013Geiger pour la Nouvelle-Z\u00e9lande.<\/label><\/p>\n<p><strong>Climat de la Nouvelle-Z\u00e9lande<\/strong><\/p>\n<p>Le climat de la Nouvelle-Z\u00e9lande est essentiellement de type maritime temp\u00e9r\u00e9 (K\u00f6ppen : Cfb), avec des temp\u00e9ratures annuelles moyennes allant de 10 \u00b0C dans le sud \u00e0 16 \u00b0C dans le nord. Les maxima et minima historiques sont de 42,4 \u00b0C \u00e0 Rangiora, Canterbury et de \u221225,6 \u00b0C \u00e0 Ranfurly, Otago. Les conditions varient consid\u00e9rablement selon les r\u00e9gions, allant d&#8217;un climat extr\u00eamement humide sur la c\u00f4te ouest de l&#8217;\u00eele du Sud \u00e0 un climat semi-aride dans le centre de l&#8217;Otago et le bassin du Mackenzie \u00e0 l&#8217;int\u00e9rieur des terres de Canterbury, et \u00e0 un climat subtropical dans le Northland.<\/p>\n<p>Parmi les sept plus grandes villes, Christchurch est la plus s\u00e8che, avec seulement 618 millim\u00e8tres de pluie par an en moyenne, et Wellington la plus humide, avec pr\u00e8s du double de cette quantit\u00e9. Auckland, Wellington et Christchurch b\u00e9n\u00e9ficient toutes d&#8217;une moyenne annuelle de plus de 2 000 heures d&#8217;ensoleillement.<\/p>\n<p>Les r\u00e9gions du sud et du sud-ouest de l&#8217;\u00eele du Sud ont un climat plus frais et plus nuageux, avec environ 1 400 \u00e0 1 600 heures de soleil ; les r\u00e9gions du nord et du nord-est de l&#8217;\u00eele du Sud sont les plus ensoleill\u00e9es du pays et re\u00e7oivent environ 2 400 \u00e0 2 500 heures de soleil. La saison des neiges s&#8217;\u00e9tend g\u00e9n\u00e9ralement de d\u00e9but juin \u00e0 d\u00e9but octobre, bien que des vagues de froid puissent survenir en dehors de cette saison. Les chutes de neige sont fr\u00e9quentes dans les r\u00e9gions de l&#8217;est et du sud de l&#8217;\u00eele du Sud et dans les zones montagneuses du pays.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carte de classification climatique de K\u00f6ppen\u2013Geiger pour la Nouvelle-Z\u00e9lande. Climat de la Nouvelle-Z\u00e9lande. Le climat de la Nouvelle-Z\u00e9lande est &#8230;<\/p>\n","protected":false},"author":1,"featured_media":54955,"template":"","categoria_ficha":[259],"class_list":["post-54954","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-la-nouvelle-zelande"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/54954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/54954\/revisions"}],"predecessor-version":[{"id":54958,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/54954\/revisions\/54958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/54955"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=54954"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=54954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}