{"id":54834,"date":"2024-11-25T18:25:38","date_gmt":"2024-11-25T18:25:38","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=54834"},"modified":"2024-11-25T18:25:38","modified_gmt":"2024-11-25T18:25:38","slug":"carte-geologique-de-l-australie","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-geologique-de-l-australie\/","title":{"rendered":"Carte g\u00e9ologique de l&#8217;Australie"},"content":{"rendered":"<p style=\"text-align: center;\"><label style=\"font-size: 15px;\">Carte g\u00e9ologique de l&#8217;Australie <a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/54834\/Carte-geologique-de-l-Australie.pdf\" target=\"_blank\" rel=\"noopener\">(format pdf)<\/a>.<\/label><\/p>\n<p><strong>G\u00e9ologie de l&#8217;Australie<\/strong><\/p>\n<p>Situ\u00e9e sur la plaque indo-australienne, l&#8217;Australie continentale est la masse continentale la plus basse et la plus primitive de la Terre, avec une histoire g\u00e9ologique relativement stable. La masse continentale comprend pratiquement tous les types de roches connus et de toutes les p\u00e9riodes g\u00e9ologiques couvrant plus de 3,8 milliards d&#8217;ann\u00e9es de l&#8217;histoire de la Terre. Le craton de Pilbara est l&#8217;une des deux seules cro\u00fbtes arch\u00e9ennes intactes de 3,6 \u00e0 2,7 Ga (milliards d&#8217;ann\u00e9es) identifi\u00e9es sur Terre.<\/p>\n<figure id=\"attachment_54837\" aria-describedby=\"caption-attachment-54837\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/54834\/Principales-regions-geologiques-de-l-Australie.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-54837\" title=\"Principales r\u00e9gions g\u00e9ologiques de l'Australie (par \u00e2ge).\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/54834\/Principales-regions-geologiques-de-l-Australie-300x276.jpg\" alt=\"Principales r\u00e9gions g\u00e9ologiques de l'Australie (par \u00e2ge).\" width=\"360\" height=\"331\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/54834\/Principales-regions-geologiques-de-l-Australie-300x276.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/54834\/Principales-regions-geologiques-de-l-Australie-768x707.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/54834\/Principales-regions-geologiques-de-l-Australie.jpg 918w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-54837\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Principales r\u00e9gions g\u00e9ologiques de l&#8217;Australie (par \u00e2ge).<\/label><\/figcaption><\/figure>\n<p>Ayant fait partie de tous les grands supercontinents, le continent australien a commenc\u00e9 \u00e0 se former apr\u00e8s la rupture du Gondwana au Permien, avec la s\u00e9paration de la masse continentale du continent africain et du sous-continent indien. Il s&#8217;est s\u00e9par\u00e9 de l&#8217;Antarctique sur une p\u00e9riode prolong\u00e9e commen\u00e7ant au Permien et se poursuivant jusqu&#8217;au Cr\u00e9tac\u00e9. Lorsque la derni\u00e8re p\u00e9riode glaciaire s&#8217;est termin\u00e9e vers 10 000 avant J.-C., la mont\u00e9e du niveau de la mer a form\u00e9 le d\u00e9troit de Bass, s\u00e9parant la Tasmanie du continent. Puis, entre 8 000 et 6 500 avant J.-C., les plaines du nord ont \u00e9t\u00e9 inond\u00e9es par la mer, s\u00e9parant la Nouvelle-Guin\u00e9e, les \u00eeles Aru et le continent australien. Le continent australien se d\u00e9place vers l&#8217;Eurasie \u00e0 un rythme de 6 \u00e0 7 centim\u00e8tres par an.<\/p>\n<p>La cro\u00fbte continentale du continent australien, \u00e0 l&#8217;exclusion des marges amincies, a une \u00e9paisseur moyenne de 38 km, avec une \u00e9paisseur comprise entre 24 km et 59 km. La g\u00e9ologie de l&#8217;Australie peut \u00eatre divis\u00e9e en plusieurs sections principales, montrant que le continent s&#8217;est d\u00e9velopp\u00e9 d&#8217;ouest en est : les boucliers cratoniques arch\u00e9ens se trouvent principalement \u00e0 l&#8217;ouest, les ceintures pliss\u00e9es prot\u00e9rozo\u00efques au centre et les bassins s\u00e9dimentaires phan\u00e9rozo\u00efques, les roches m\u00e9tamorphiques et ign\u00e9es \u00e0 l&#8217;est.<\/p>\n<p>L&#8217;Australie continentale et la Tasmanie sont situ\u00e9es au milieu de la plaque tectonique et ne comptent pas de volcans actifs, mais en raison du passage au-dessus du point chaud de l&#8217;Australie orientale, un volcanisme r\u00e9cent s&#8217;est produit pendant l&#8217;Holoc\u00e8ne, dans la province volcanique de Newer, \u00e0 l&#8217;ouest de Victoria et au sud-est de l&#8217;Australie-M\u00e9ridionale. Le volcanisme est \u00e9galement pr\u00e9sent sur l&#8217;\u00eele de Nouvelle-Guin\u00e9e (consid\u00e9r\u00e9e g\u00e9ologiquement comme faisant partie du continent australien) et dans le territoire ext\u00e9rieur australien des \u00eeles Heard et McDonald. L&#8217;activit\u00e9 sismique sur le continent australien et en Tasmanie est \u00e9galement faible, le plus grand nombre de d\u00e9c\u00e8s ayant eu lieu lors du tremblement de terre de Newcastle en 1989.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>G\u00e9ologie de l&#8217;Australie. Situ\u00e9e sur la plaque indo-australienne, l&#8217;Australie continentale est la masse continentale la plus basse et la plus primitive de la &#8230;<\/p>\n","protected":false},"author":1,"featured_media":54835,"template":"","categoria_ficha":[252],"class_list":["post-54834","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-l-australie"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/54834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/54834\/revisions"}],"predecessor-version":[{"id":55375,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/54834\/revisions\/55375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/54835"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=54834"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=54834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}