{"id":53461,"date":"2024-11-03T23:59:32","date_gmt":"2024-11-03T23:59:32","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=53461"},"modified":"2024-11-07T13:24:06","modified_gmt":"2024-11-07T13:24:06","slug":"carte-politique-de-l-indonesie","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-politique-de-l-indonesie\/","title":{"rendered":"Carte politique de l\u2019Indon\u00e9sie"},"content":{"rendered":"<p style=\"text-align: center;\"><label style=\"font-size: 15px;\">Carte politique de l\u2019Indon\u00e9sie <a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/53461\/Carte-politique-de-l-Indonesie.pdf\" target=\"_blank\" rel=\"noopener\">(format pdf)<\/a>.<\/label><\/p>\n<figure id=\"attachment_53614\" aria-describedby=\"caption-attachment-53614\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/53461\/Carte-politique-de-l-Indonesie-de-1984.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-53614\" title=\"Carte politique de l\u2019Indon\u00e9sie de 1984.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/53461\/Carte-politique-de-l-Indonesie-de-1984-300x214.jpg\" alt=\"Carte politique de l\u2019Indon\u00e9sie de 1984.\" width=\"360\" height=\"257\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/53461\/Carte-politique-de-l-Indonesie-de-1984-300x214.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/53461\/Carte-politique-de-l-Indonesie-de-1984-1024x731.jpg 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/53461\/Carte-politique-de-l-Indonesie-de-1984-768x548.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/53461\/Carte-politique-de-l-Indonesie-de-1984-1536x1096.jpg 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/53461\/Carte-politique-de-l-Indonesie-de-1984-2048x1462.jpg 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/53461\/Carte-politique-de-l-Indonesie-de-1984-1600x1142.jpg 1600w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-53614\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte politique de l\u2019Indon\u00e9sie de 1984.<\/label><\/figcaption><\/figure>\n<p>L&#8217;Indon\u00e9sie est politiquement une r\u00e9publique avec un r\u00e9gime pr\u00e9sidentiel, un \u00c9tat unitaire divis\u00e9 en une succession de quatre niveaux d&#8217;unit\u00e9s de gouvernement territoriales qui sont, en allant de la plus grande \u00e0 la plus petite unit\u00e9 :<\/p>\n<ul>\n<li>1<sup>er<\/sup> niveau : la provinsi (province) ;<\/li>\n<li>2<sup>e<\/sup> niveau : le kabupaten (d\u00e9partement) et la kota (ville) ;<\/li>\n<li>3<sup>e<\/sup> niveau : le kecamatan (district) ;<\/li>\n<li>4<sup>e<\/sup> niveau, selon la r\u00e9gion ou la province : le kelurahan (commune), le desa (village), le gampong (village en Aceh), le nagari (village en pays minangkabau au Sumatra oriental), le kampung (village en Papouasie).<\/li>\n<\/ul>\n<p>Le village est le niveau le plus bas de l&#8217;administration gouvernementale. Il est divis\u00e9 en plusieurs groupes communautaires (rukun warga, RW), eux-m\u00eames subdivis\u00e9s en groupes de quartier (rukun tetangga, RT). \u00c0 Java, le village (desa) est divis\u00e9 en unit\u00e9s plus petites appel\u00e9es dusun ou dukuh (hameaux), qui sont identiques \u00e0 RW.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Indon\u00e9sie est politiquement une r\u00e9publique avec un r\u00e9gime pr\u00e9sidentiel, un \u00c9tat unitaire divis\u00e9 en une succession de quatre niveaux d&#8217;unit\u00e9s de gouvernement <\/p>\n","protected":false},"author":1,"featured_media":53463,"template":"","categoria_ficha":[160],"class_list":["post-53461","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-l-indonesie"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/53461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":4,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/53461\/revisions"}],"predecessor-version":[{"id":53617,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/53461\/revisions\/53617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/53463"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=53461"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=53461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}