{"id":531,"date":"2022-02-04T00:12:40","date_gmt":"2022-02-04T00:12:40","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=531"},"modified":"2023-03-25T20:54:20","modified_gmt":"2023-03-25T20:54:20","slug":"carte-de-l-ile-de-saint-martin","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-de-l-ile-de-saint-martin\/","title":{"rendered":"Carte de l&#8217;\u00eele de Saint-Martin"},"content":{"rendered":"<p><strong>Carte de l&#8217;\u00eele de Saint-Martin<\/strong>, une \u00eele du nord-est de la mer des Cara\u00efbes, \u00e0 environ 300 km \u00e0 l&#8217;est de Porto Rico. L&#8217;\u00eele de 87 kilom\u00e8tres carr\u00e9s est divis\u00e9e \u00e0 environ 60:40 entre la R\u00e9publique fran\u00e7aise (53 km\u00b2) et le Royaume des Pays-Bas (34 km\u00b2), mais les deux parties ont \u00e0 peu pr\u00e8s la m\u00eame population. La division date de 1648. La partie sud n\u00e9erlandaise comprend Sint Maarten et est l&#8217;un des quatre pays constitutifs qui forment le Royaume des Pays-Bas. La partie nord de la France comprend la collectivit\u00e9 de Saint-Martin et est une collectivit\u00e9 d&#8217;outre-mer de la R\u00e9publique fran\u00e7aise. Faisant partie de la France, la partie fran\u00e7aise de l&#8217;\u00eele fait \u00e9galement partie de l&#8217;Union europ\u00e9enne.<\/p>\n<figure id=\"attachment_10240\" aria-describedby=\"caption-attachment-10240\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/10239\/Image-satellite-de-l-ile-de-Saint-Martin.png\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-10240\" style=\"width: 100%; max-width: 360px; height: auto;\" title=\"Image satellite de l'\u00eele de Saint-Martin.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/10239\/Image-satellite-de-l-ile-de-Saint-Martin-273x300.png\" alt=\"Image satellite de l'\u00eele de Saint-Martin.\" width=\"360\" height=\"395\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/10239\/Image-satellite-de-l-ile-de-Saint-Martin-273x300.png 273w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/10239\/Image-satellite-de-l-ile-de-Saint-Martin-300x329.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/10239\/Image-satellite-de-l-ile-de-Saint-Martin.png 536w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-10240\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Image satellite de l&#8217;\u00eele de Saint-Martin.<\/label><\/figcaption><\/figure>\n<p>Au 1er janvier 2009, la population de l&#8217;ensemble de l&#8217;\u00eele \u00e9tait de 77\u00a0741 habitants, dont 40\u00a0917 du c\u00f4t\u00e9 n\u00e9erlandais et 36\u00a0824 du c\u00f4t\u00e9 fran\u00e7ais.<\/p>\n<ul>\n<li>Superficie totale de Saint-Martin 87 km\u00b2<\/li>\n<li>En 2009 la population de Saint-Martin \u00e9tait de 77,741<\/li>\n<li>Les capitales de l&#8217;\u00eele sont Marigot et Philipsburg<\/li>\n<\/ul>\n<p>Le nom traditionnel pr\u00e9colonial de l&#8217;\u00eele est Oualichi qui signifie \u00ab l&#8217;\u00eele des femmes \u00bb.<\/p>\n<p>Collectivement, les deux territoires sont connus sous le nom de \u00ab Saint-Martin \/ Sint Maarten \u00bb, ou parfois \u00ab SXM \u00bb, l&#8217;identifiant IATA de l&#8217;a\u00e9roport international Princesse-Juliana, le principal a\u00e9roport de l&#8217;\u00eele. Saint-Martin (la partie fran\u00e7aise) a re\u00e7u le code ISO 3166-1 MF en octobre 2007. En 2010, la partie n\u00e9erlandaise a vu son statut chang\u00e9 en celui d&#8217;un pays du Royaume des Pays-Bas et a re\u00e7u le code SX.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carte de l&#8217;\u00eele de Saint-Martin, une \u00eele du nord-est de la mer des Cara\u00efbes, \u00e0 environ 300 km \u00e0 l&#8217;est de Porto Rico. L&#8217;\u00eele de 87 kilom\u00e8tres carr\u00e9s est divis\u00e9e \u00e0 environ 60:40 entre la R\u00e9publique fran\u00e7aise (53 km\u00b2) et le Royaume des Pays-Bas (34 km\u00b2), mais les deux parties ont \u00e0 peu pr\u00e8s la m\u00eame population. La divis<\/p>\n","protected":false},"author":1,"featured_media":11616,"template":"","categoria_ficha":[76],"class_list":["post-531","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-l-ile-de-saint-martin"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":11,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/531\/revisions"}],"predecessor-version":[{"id":37169,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/531\/revisions\/37169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/11616"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=531"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}