{"id":51120,"date":"2024-09-26T00:00:06","date_gmt":"2024-09-26T00:00:06","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=51120"},"modified":"2024-09-26T00:00:06","modified_gmt":"2024-09-26T00:00:06","slug":"carte-de-gwanghwamun-seoul","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-de-gwanghwamun-seoul\/","title":{"rendered":"Carte de Gwanghwamun, S\u00e9oul"},"content":{"rendered":"<p style=\"text-align: center;\"><label style=\"font-size: 15px;\">Carte de Gwanghwamun, S\u00e9oul.<\/label><\/p>\n<p>Gwanghwamun (cor\u00e9en : \uad11\ud654\ubb38 ; hanja : \u5149\u5316\u9580) ou Porte de Gwanghwa est la porte principale et la plus grande du palais de Gyeongbok, \u00e0 Jongno-gu, S\u00e9oul, Cor\u00e9e du Sud. Elle est situ\u00e9e \u00e0 une intersection \u00e0 trois voies \u00e0 l&#8217;extr\u00e9mit\u00e9 nord de Sejongno. En tant que monument et symbole de la longue histoire de S\u00e9oul en tant que capitale pendant la p\u00e9riode Joseon, la porte a travers\u00e9 de multiples p\u00e9riodes de destruction et de d\u00e9labrement. Les derniers travaux de restauration \u00e0 grande \u00e9chelle sur la porte ont \u00e9t\u00e9 termin\u00e9s et elle a \u00e9t\u00e9 ouverte au public le 15 ao\u00fbt 2010.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gwanghwamun (cor\u00e9en : \uad11\ud654\ubb38 ; hanja : \u5149\u5316\u9580) ou Porte de Gwanghwa est la porte principale et la plus grande du palais de Gyeongbok, \u00e0 Jongno-gu, S\u00e9oul, Cor\u00e9e du Sud<\/p>\n","protected":false},"author":1,"featured_media":51121,"template":"","categoria_ficha":[2041],"class_list":["post-51120","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-seoul"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/51120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/51120\/revisions"}],"predecessor-version":[{"id":51122,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/51120\/revisions\/51122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/51121"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=51120"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=51120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}