{"id":501,"date":"2022-02-04T00:12:22","date_gmt":"2022-02-04T00:12:22","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=501"},"modified":"2022-11-29T22:11:47","modified_gmt":"2022-11-29T22:11:47","slug":"image-satellite-de-porto-rico","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/image-satellite-de-porto-rico\/","title":{"rendered":"Image satellite de Porto Rico"},"content":{"rendered":"<p>Une vue de <strong>Porto Rico<\/strong> (en haut \u00e0 gauche) et des <strong>\u00eeles des Petites Antilles<\/strong>. Le volcan de la Soufri\u00e8re sur l&#8217;\u00eele de Montserrat a commenc\u00e9 \u00e0 \u00e9mettre de la vapeur et des cendres le 9 f\u00e9vrier 2006. L&#8217;activit\u00e9 \u00e0 faible niveau s&#8217;est poursuivie pendant plusieurs jours. Le volcan a produit un autre panache le 20 mars 2006, qui est captur\u00e9 sur cette image. Le panache de cendres beige p\u00e2le du volcan souffle vers l&#8217;ouest au-dessus de la mer des Cara\u00efbes. Le contour rouge montre o\u00f9 le satellite a d\u00e9tect\u00e9 une anomalie thermique, une zone o\u00f9 la surface du sol \u00e9tait nettement plus chaude que son environnement. Image satellite de Porto Rico et des \u00eeles des Petites Antilles courtoisie de la NASA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une vue de Porto Rico (en haut \u00e0 gauche) et des \u00eeles des Petites Antilles. Le volcan de la Soufri\u00e8re sur l&#8217;\u00eele de Montserrat a commenc\u00e9 \u00e0 \u00e9mettre de la vapeur et des cendres le 9 f\u00e9vrier 2006. L&#8217;activit\u00e9 \u00e0 faible niveau s&#8217;est poursuivie pendant plusieurs jours. Le volcan a produit un autre panache l<\/p>\n","protected":false},"author":1,"featured_media":5710,"template":"","categoria_ficha":[72],"class_list":["post-501","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-porto-rico"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":5,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/501\/revisions"}],"predecessor-version":[{"id":26598,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/501\/revisions\/26598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/5710"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=501"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}