{"id":491,"date":"2022-02-04T00:12:17","date_gmt":"2022-02-04T00:12:17","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=491"},"modified":"2025-01-02T02:16:30","modified_gmt":"2025-01-02T02:16:30","slug":"carte-du-panama","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-du-panama\/","title":{"rendered":"Carte du Panama"},"content":{"rendered":"<p><strong>Carte du Panama <a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Carte-du-Panama.pdf\" target=\"_blank\" rel=\"noopener\">(format pdf)<\/a><\/strong>, officiellement la R\u00e9publique du Panama, un pays transr\u00e9gional situ\u00e9 entre l&#8217;Am\u00e9rique du Sud et l&#8217;Am\u00e9rique centrale, bord\u00e9 par le Costa Rica \u00e0 l&#8217;ouest, la Colombie au sud-est, la mer des Cara\u00efbes au nord et l&#8217;oc\u00e9an Pacifique au sud. La capitale et la plus grande ville est la ville de Panama, dont la zone m\u00e9tropolitaine abrite pr\u00e8s de la moiti\u00e9 des plus de 4 millions d&#8217;habitants du pays.<\/p>\n<ul>\n<li>\n<figure id=\"attachment_56274\" aria-describedby=\"caption-attachment-56274\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Image-composite-satellite-du-Panama.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-56274\" title=\"Image composite satellite du Panama de la NASA.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Image-composite-satellite-du-Panama-300x127.jpg\" alt=\"Image composite satellite du Panama de la NASA.\" width=\"360\" height=\"152\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Image-composite-satellite-du-Panama-300x127.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Image-composite-satellite-du-Panama-1024x432.jpg 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Image-composite-satellite-du-Panama-768x324.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Image-composite-satellite-du-Panama.jpg 1422w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-56274\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Image composite satellite du Panama de la NASA.<\/label><\/figcaption><\/figure>\n<p>Superficie totale du Panama 75,517 km\u00b2<\/li>\n<li>En 2021 la population du Panama \u00e9tait de 4,379,039<\/li>\n<li>La capitale du pays est Panama<\/li>\n<li>Les plus grandes villes du Panama sont: Panama, San Miguelito, Las Cumbres, La Chorrera, Tocumen.<\/li>\n<\/ul>\n<p>Le Panama \u00e9tait habit\u00e9 par des tribus autochtones avant l&#8217;arriv\u00e9e des colons espagnols au XVI<sup>e<\/sup> si\u00e8cle. Il rompu avec l&#8217;Espagne en 1821 et fit partie de la Grande Colombie. Apr\u00e8s la dissolution de la Grande Colombie en 1831, Panama et Nueva Granada devinrent finalement la R\u00e9publique de Colombie. Avec le soutien des \u00c9tats-Unis, le Panama a fait s\u00e9cession de la Colombie en 1903, ce qui permis au Corps du g\u00e9nie de l&#8217;arm\u00e9e de terre des \u00c9tats-Unis d&#8217;achever la construction du canal de Panama entre 1904 et 1914. Les trait\u00e9s Torrijos-Carter de 1977 ont convenu de transf\u00e9rer le canal du Des \u00c9tats-Unis au Panama le 31 d\u00e9cembre 1999. Le territoire environnant a \u00e9t\u00e9 rendu pour la premi\u00e8re fois en 1979.<\/p>\n<figure id=\"attachment_56272\" aria-describedby=\"caption-attachment-56272\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Carte-du-Panama-de-1906.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-56272\" title=\"Carte du Panama de 1906.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Carte-du-Panama-de-1906-300x184.jpg\" alt=\"Carte du Panama de 1906.\" width=\"360\" height=\"220\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Carte-du-Panama-de-1906-300x184.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Carte-du-Panama-de-1906-1024x627.jpg 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Carte-du-Panama-de-1906-768x470.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Carte-du-Panama-de-1906-1536x941.jpg 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/491\/Carte-du-Panama-de-1906.jpg 1600w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-56272\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte du Panama de 1906.<\/label><\/figcaption><\/figure>\n<p>Les revenus des p\u00e9ages du canal continuent de repr\u00e9senter une part importante du PIB du Panama, bien que le commerce, la banque et le tourisme soient des secteurs majeurs et en croissance. Il est consid\u00e9r\u00e9 comme une \u00e9conomie \u00e0 revenu \u00e9lev\u00e9. En 2019, le Panama se classait au 57<sup>e<\/sup> rang mondial en termes d&#8217;indice de d\u00e9veloppement humain. En 2018, le Panama \u00e9tait class\u00e9 au septi\u00e8me rang des \u00e9conomies les plus comp\u00e9titives d&#8217;Am\u00e9rique latine, selon l&#8217;indice de comp\u00e9titivit\u00e9 mondiale du Forum \u00e9conomique mondial. Couvrant environ 40 pour cent de sa superficie, les jungles du Panama abritent une abondance de plantes et d&#8217;animaux tropicaux, dont certains ne se trouvent nulle part ailleurs sur terre. Le Panama est un membre fondateur des Nations Unies et d&#8217;autres organisations internationales telles que l&#8217;OEA, l&#8217;ALADI, le G77, l&#8217;OMS et le mouvement des non-align\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carte du Panama (format pdf), officiellement la R\u00e9publique du Panama, un pays transr\u00e9gional situ\u00e9 entre l&#8217;Am\u00e9rique du Sud et l&#8217;Am\u00e9rique centrale, bord\u00e9 par &#8230;<\/p>\n","protected":false},"author":1,"featured_media":492,"template":"","categoria_ficha":[71],"class_list":["post-491","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-du-panama"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/491\/revisions"}],"predecessor-version":[{"id":56275,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/491\/revisions\/56275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/492"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=491"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}