{"id":48685,"date":"2024-07-17T23:56:43","date_gmt":"2024-07-17T23:56:43","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=48685"},"modified":"2024-07-17T23:56:43","modified_gmt":"2024-07-17T23:56:43","slug":"armoiries-de-l-ouganda","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/armoiries-de-l-ouganda\/","title":{"rendered":"Armoiries de l&#8217;Ouganda"},"content":{"rendered":"<p>Les armoiries de l&#8217;Ouganda ont \u00e9t\u00e9 adopt\u00e9es trois semaines avant la proclamation de l&#8217;ind\u00e9pendance par le Conseil l\u00e9gislatif ougandais. Le 1<sup>er<\/sup> octobre 1962, les armes furent approuv\u00e9es par le gouverneur de l&#8217;Ouganda, Walter Coutts, et officiellement \u00e9tablies par la loi le 9 octobre.<\/p>\n<p>Le bouclier et les lances repr\u00e9sentent la volont\u00e9 du peuple ougandais de d\u00e9fendre son pays. Il y a trois images sur le bouclier : celles du dessus repr\u00e9sentent les vagues du lac Victoria et du lac Albert ; le soleil au centre repr\u00e9sente les nombreux jours de soleil \u00e9clatant dont b\u00e9n\u00e9ficie l&#8217;Ouganda ; et le tambour traditionnel en bas symbolise la danse et la convocation des gens aux r\u00e9unions et aux c\u00e9r\u00e9monies.<\/p>\n<p>L&#8217;explication ci-dessus, \u00e0 propos du symbolisme du tambour, est une d\u00e9formation survenue apr\u00e8s la sanglante crise nationale de 1966, lorsque le Premier ministre de l&#8217;\u00e9poque, Milton Obote, a lanc\u00e9 une violente attaque militaire contre le roi du royaume du Buganda, dans le centre de l&#8217;Ouganda. , Edward Mutesa II, qui \u00e9tait alors pr\u00e9sident de c\u00e9r\u00e9monie de l&#8217;\u00c9tat. L&#8217;ann\u00e9e suivante, en 1967, la constitution du pays fut abrog\u00e9e et remplac\u00e9e par une nouvelle qui abolit les anciennes monarchies du pays : les royaumes du Buganda, de Bunyoro, d&#8217;Ankole, de Toro et la Principaut\u00e9 de Busoga, transformant l&#8217;Ouganda en une r\u00e9publique et faisant de Milton Obote pr\u00e9sident dot\u00e9 de pouvoirs ex\u00e9cutifs illimit\u00e9s.<\/p>\n<p>Avant le r\u00e8gne d&#8217;Obote, le tambour symbolisait la royaut\u00e9 et l&#8217;autorit\u00e9 des rois ougandais. Dans le m\u00eame ordre d\u2019id\u00e9es, les rois d\u2019Ouganda ont \u00e9t\u00e9 les premiers \u00e0 utiliser le bouclier africain traditionnel en forme de lentille dans leurs armes h\u00e9raldiques.<\/p>\n<p>Le blason est flanqu\u00e9, \u00e0 droite par une Grue royale qui est l&#8217;oiseau officiel du pays. \u00c0 gauche il y a un Cob de Thomas (antilope) qui ici symbolise la faune abondante.<\/p>\n<p>Le monticule vert symbolise la terre fertile, et est situ\u00e9 sur une repr\u00e9sentation du Nil. Deux des plantes principales du pays (le coton et le caf\u00e9) flanquent le fleuve. Dans la partie inf\u00e9rieure, on peut lire la devise nationale : \u00ab For God and My Country \u00bb (\u00ab Pour Dieu et mon Pays \u00bb).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les armoiries de l&#8217;Ouganda ont \u00e9t\u00e9 adopt\u00e9es trois semaines avant la proclamation de l&#8217;ind\u00e9pendance par le Conseil l\u00e9gislatif ougandais. Le 1er octobre 1962 &#8230;<\/p>\n","protected":false},"author":1,"featured_media":48686,"template":"","categoria_ficha":[240],"class_list":["post-48685","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-l-ouganda"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/48685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/48685\/revisions"}],"predecessor-version":[{"id":48688,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/48685\/revisions\/48688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/48686"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=48685"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=48685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}