{"id":45980,"date":"2024-04-12T19:02:34","date_gmt":"2024-04-12T19:02:34","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=45980"},"modified":"2024-04-12T19:06:51","modified_gmt":"2024-04-12T19:06:51","slug":"carte-de-la-ville-de-varsovie-pologne","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-de-la-ville-de-varsovie-pologne\/","title":{"rendered":"Carte de la ville de Varsovie, Pologne"},"content":{"rendered":"<p>Carte de la ville de Varsovie, la capitale et la plus grande ville de Pologne. La m\u00e9tropole se situe sur la Vistule, dans le centre-est de la Pologne. Sa population est officiellement estim\u00e9e \u00e0 1,86 millions d&#8217;habitants au sein d&#8217;une grande zone m\u00e9tropolitaine de 3,27 millions d&#8217;habitants, ce qui fait de Varsovie la 7<sup>\u00e8me<\/sup> ville la plus peupl\u00e9e de l&#8217;Union europ\u00e9enne. La superficie de la ville mesure 517 km\u00b2 et comprend 18 districts, tandis que la zone m\u00e9tropolitaine s&#8217;\u00e9tend sur 6 100 km\u00b2. Varsovie est une ville mondiale alpha, un p\u00f4le culturel, politique et \u00e9conomique majeur et le si\u00e8ge du gouvernement du pays. C&#8217;est \u00e9galement la capitale de la vo\u00efvodie de Mazovie.<\/p>\n<figure id=\"attachment_45982\" aria-describedby=\"caption-attachment-45982\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Plan-de-localisation-de-Varsovie-en-Pologne.png\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-45982\" title=\"Plan de localisation de Varsovie en Pologne.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Plan-de-localisation-de-Varsovie-en-Pologne-300x292.png\" alt=\"Plan de localisation de Varsovie en Pologne.\" width=\"360\" height=\"350\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Plan-de-localisation-de-Varsovie-en-Pologne-300x292.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Plan-de-localisation-de-Varsovie-en-Pologne-1024x995.png 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Plan-de-localisation-de-Varsovie-en-Pologne-768x746.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Plan-de-localisation-de-Varsovie-en-Pologne-1536x1493.png 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Plan-de-localisation-de-Varsovie-en-Pologne-2048x1991.png 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Plan-de-localisation-de-Varsovie-en-Pologne-1600x1555.png 1600w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-45982\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Plan de localisation de Varsovie en Pologne.<\/label><\/figcaption><\/figure>\n<p>Varsovie trouve ses origines dans un petit village de p\u00eacheurs de Mazovie. La ville a pris de l&#8217;importance \u00e0 la fin du XVI<sup>e<\/sup> si\u00e8cle, lorsque Sigismond III a d\u00e9cid\u00e9 de d\u00e9placer la capitale polonaise et sa cour royale de Cracovie. Varsovie a \u00e9t\u00e9 la capitale de facto du Commonwealth polono-lituanien jusqu&#8217;en 1795, puis le si\u00e8ge du duch\u00e9 de Varsovie de Napol\u00e9on. Le XIX<sup>e<\/sup> si\u00e8cle et sa r\u00e9volution industrielle apportent un boom d\u00e9mographique qui en fait l\u2019une des villes les plus grandes et les plus dens\u00e9ment peupl\u00e9es d\u2019Europe. Connue \u00e0 l&#8217;\u00e9poque pour son architecture \u00e9l\u00e9gante et ses boulevards, Varsovie a \u00e9t\u00e9 bombard\u00e9e et assi\u00e9g\u00e9e au d\u00e9but de la Seconde Guerre mondiale en 1939. Une grande partie de la ville historique a \u00e9t\u00e9 d\u00e9truite et sa population diversifi\u00e9e d\u00e9cim\u00e9e par l&#8217;insurrection du ghetto en 1943, l&#8217;insurrection g\u00e9n\u00e9rale de Varsovie en 1944 et un rasage syst\u00e9matique.<\/p>\n<p>Varsovie est desservie par deux a\u00e9roports internationaux, le plus fr\u00e9quent\u00e9 \u00e9tant Varsovie Chopin ainsi que le plus petit Varsovie Modlin destin\u00e9 aux transporteurs \u00e0 bas prix. Les principaux services de transports publics op\u00e9rant dans la ville comprennent le m\u00e9tro de Varsovie, les bus, le service ferroviaire de banlieue et un vaste r\u00e9seau de tramway. La ville est un centre important de recherche et de d\u00e9veloppement, d&#8217;externalisation des processus commerciaux et d&#8217;externalisation des technologies de l&#8217;information. La Bourse de Varsovie est la plus grande et la plus importante d&#8217;Europe centrale et orientale. Frontex, l&#8217;agence de l&#8217;Union europ\u00e9enne pour la s\u00e9curit\u00e9 des fronti\u00e8res ext\u00e9rieures, et le Bureau des institutions d\u00e9mocratiques et des droits de l&#8217;homme (ODIHR), l&#8217;une des principales institutions de l&#8217;Organisation pour la s\u00e9curit\u00e9 et la coop\u00e9ration en Europe, ont leur si\u00e8ge \u00e0 Varsovie. En 2022, Varsovie poss\u00e8de l&#8217;un des plus grands nombres de gratte-ciel d&#8217;Europe, tandis que Varso Tower est le plus haut b\u00e2timent de l&#8217;Union europ\u00e9enne.<\/p>\n<figure id=\"attachment_45983\" aria-describedby=\"caption-attachment-45983\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Division-administrative-de-Varsovie-Pologne-depuis-2002.png\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-45983\" title=\"Division administrative de Varsovie, Pologne depuis 2002.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Division-administrative-de-Varsovie-Pologne-depuis-2002-283x300.png\" alt=\"Division administrative de Varsovie, Pologne depuis 2002.\" width=\"360\" height=\"382\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Division-administrative-de-Varsovie-Pologne-depuis-2002-283x300.png 283w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Division-administrative-de-Varsovie-Pologne-depuis-2002-966x1024.png 966w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Division-administrative-de-Varsovie-Pologne-depuis-2002-768x815.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Division-administrative-de-Varsovie-Pologne-depuis-2002-1448x1536.png 1448w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Division-administrative-de-Varsovie-Pologne-depuis-2002-300x318.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Division-administrative-de-Varsovie-Pologne-depuis-2002-1509x1600.png 1509w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Division-administrative-de-Varsovie-Pologne-depuis-2002.png 1931w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-45983\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Division administrative de Varsovie, Pologne depuis 2002.<\/label><\/figcaption><\/figure>\n<p>La ville abrite des universit\u00e9s renomm\u00e9es telles que l&#8217;Universit\u00e9 de Varsovie, l&#8217;\u00c9cole polytechnique de Varsovie, l&#8217;\u00c9cole des hautes \u00e9tudes commerciales de Varsovie, l&#8217;universit\u00e9 de musique Fr\u00e9d\u00e9ric-Chopin et l&#8217;Acad\u00e9mie Leon-Ko\u017ami\u0144ski. Elle accueille \u00e9galement l&#8217;Acad\u00e9mie polonaise des sciences, l&#8217;Orchestre philharmonique de Varsovie, le Mus\u00e9e national, la galerie d&#8217;art Zach\u0119ta et le Grand Th\u00e9\u00e2tre \u2014 Op\u00e9ra National de Varsovie, le plus grand du genre au monde. La vieille ville reconstruite, qui repr\u00e9sente des exemples de presque tous les styles architecturaux et p\u00e9riodes historiques europ\u00e9ens, a \u00e9t\u00e9 class\u00e9e au patrimoine mondial en 1980. Parmi les autres attractions architecturales figurent le palais royal, la colonne de Sigismond, le palais de Wilan\u00f3w, le palais \u0141azienki, la cath\u00e9drale Saint-Jean, la Place du March\u00e9-de-la-Vieille-Ville et de nombreuses \u00e9glises et demeures le long de la voie Royale. Le zoo de Varsovie fait partie des jardins zoologiques les plus grands et les plus visit\u00e9s du pays. La ville poss\u00e8de des sc\u00e8nes artistiques et de clubs florissantes, des restaurants gastronomiques et de grands espaces verts urbains, avec environ un quart de la superficie de la ville occup\u00e9e par des parcs. Dans le domaine sportif, la ville est connue pour abriter le club de football de premier plan Legia Varsovie, le marathon de Varsovie et le stade national de football polonais Stadion Narodowy.<\/p>\n<figure id=\"attachment_45984\" aria-describedby=\"caption-attachment-45984\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Image-satellite-de-Varsovie-2020.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-45984\" title=\"Image satellite de Varsovie.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Image-satellite-de-Varsovie-2020-300x300.jpg\" alt=\"Image satellite de Varsovie.\" width=\"400\" height=\"399\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Image-satellite-de-Varsovie-2020-300x299.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Image-satellite-de-Varsovie-2020-1024x1020.jpg 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Image-satellite-de-Varsovie-2020-150x150.jpg 150w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Image-satellite-de-Varsovie-2020-768x765.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Image-satellite-de-Varsovie-2020-1536x1530.jpg 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Image-satellite-de-Varsovie-2020-2048x2040.jpg 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/45980\/Image-satellite-de-Varsovie-2020-1600x1594.jpg 1600w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><figcaption id=\"caption-attachment-45984\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Image satellite de Varsovie.<\/label><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Carte de la ville de Varsovie, la capitale et la plus grande ville de Pologne. La m&#8230;<\/p>\n","protected":false},"author":1,"featured_media":45981,"template":"","categoria_ficha":[114],"class_list":["post-45980","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-la-pologne"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/45980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":4,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/45980\/revisions"}],"predecessor-version":[{"id":45986,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/45980\/revisions\/45986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/45981"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=45980"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=45980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}