{"id":45338,"date":"2024-03-28T00:27:20","date_gmt":"2024-03-28T00:27:20","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=45338"},"modified":"2024-03-28T00:27:20","modified_gmt":"2024-03-28T00:27:20","slug":"drapeau-de-l-italie","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/drapeau-de-l-italie\/","title":{"rendered":"Drapeau de l&#8217;Italie"},"content":{"rendered":"<p>Le drapeau italien est constitu\u00e9 de trois bandes verticales \u00e9gales de couleur verte (c\u00f4t\u00e9 m\u00e2t), blanche et rouge ; design inspir\u00e9 du drapeau fran\u00e7ais apport\u00e9 en Italie par Napol\u00e9on en 1797 ; les couleurs sont celles de Milan (rouge et blanc) combin\u00e9es \u00e0 la couleur verte de l&#8217;uniforme de la garde civique milanaise.<\/p>\n<p>remarque : similaire au drapeau du Mexique, qui est plus long, utilise des nuances plus fonc\u00e9es de vert et de rouge et a ses armoiries centr\u00e9es sur la bande blanche ; l&#8217;Irlande, qui est plus longue et est verte (c\u00f4t\u00e9 m\u00e2t), blanche et orange ; \u00e9galement similaire au drapeau de la C\u00f4te d&#8217;Ivoire, dont les couleurs sont invers\u00e9es &#8211; orange (c\u00f4t\u00e9 m\u00e2t), blanc et vert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le drapeau italien est constitu\u00e9 de trois bandes verticales \u00e9gales de couleur verte (c\u00f4t\u00e9 m\u00e2t), blanche et rouge ; design inspir\u00e9 du drapeau fran\u00e7ais apport\u00e9 en<\/p>\n","protected":false},"author":1,"featured_media":45339,"template":"","categoria_ficha":[121],"class_list":["post-45338","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-l-italie"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/45338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/45338\/revisions"}],"predecessor-version":[{"id":45351,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/45338\/revisions\/45351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/45339"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=45338"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=45338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}