{"id":44255,"date":"2023-09-30T14:59:10","date_gmt":"2023-09-30T14:59:10","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=44255"},"modified":"2023-09-30T15:00:36","modified_gmt":"2023-09-30T15:00:36","slug":"plan-d-acces-routier-a-bale","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/plan-d-acces-routier-a-bale\/","title":{"rendered":"Plan d&#8217;acc\u00e8s routier \u00e0 B\u00e2le"},"content":{"rendered":"<p style=\"text-align: center;\"><label style=\"font-size: 15px;\">Plan d&#8217;acc\u00e8s routier \u00e0 B\u00e2le.<\/label><\/p>\n<p>La ville de B\u00e2le est un carrefour d&#8217;importantes liaisons routi\u00e8res vers l&#8217;Allemagne et la France. Les deux routes europ\u00e9ennes de haut niveau 25 et 35 (A2 et A3 ou A5 et A35 en Allemagne\/France) traversent B\u00e2le dans le sens nord-sud. Les routes europ\u00e9ennes de cat\u00e9gorie A qui ont la m\u00eame direction sont g\u00e9n\u00e9ralement plus \u00e9loign\u00e9es les unes des autres.<\/p>\n<p>Depuis Lucerne et Zurich, l&#8217;A2 et l&#8217;A3 (E 25 et E 35) relient l&#8217;A5 allemande (E35) vers Karlsruhe et l&#8217;A35 fran\u00e7aise (E25) vers Mulhouse et Strasbourg via les tangentes est et nord. Il existe \u00e9galement les autoroutes urbaines A18 et A22, qui relient la banlieue du canton de B\u00e2le-Campagne \u00e0 B\u00e2le. Les autoroutes A98 et A861, qui circulent enti\u00e8rement sur le territoire allemand, servent de contournement au contournement oriental, massivement surcharg\u00e9.<\/p>\n<p>Cinq ponts routiers et un pont ferroviaire relient les deux parties de B\u00e2le au-dessus du Rhin. En direction de la rivi\u00e8re, il s&#8217;agit du pont de la For\u00eat-Noire (Schwarzwaldbr\u00fccke (pont autoroutier et ferroviaire)), du pont Wettstein, du pont du milieu (Mittlere Br\u00fccke), du pont Johanniter et du pont \u00e0 deux \u00e9tages Dreirosen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ville de B\u00e2le est un carrefour d&#8217;importantes liaisons routi\u00e8res vers l&#8217;Allemagne et la France. Les deux routes europ\u00e9ennes de haut niveau 25 et 35 (A2 et A3 <\/p>\n","protected":false},"author":1,"featured_media":44256,"template":"","categoria_ficha":[292],"class_list":["post-44255","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-bale"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/44255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/44255\/revisions"}],"predecessor-version":[{"id":44258,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/44255\/revisions\/44258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/44256"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=44255"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=44255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}