{"id":279,"date":"2022-02-04T00:10:10","date_gmt":"2022-02-04T00:10:10","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=279"},"modified":"2022-08-07T18:48:38","modified_gmt":"2022-08-07T18:48:38","slug":"le-drapeau-d-aruba","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/le-drapeau-d-aruba\/","title":{"rendered":"Le drapeau d&#8217;Aruba"},"content":{"rendered":"<p><strong>Le drapeau d&#8217;Aruba<\/strong> est bleu, avec deux bandes jaunes horizontales \u00e9troites sur la partie inf\u00e9rieure et une \u00e9toile rouge \u00e0 quatre branches soulign\u00e9e de blanc dans le coin sup\u00e9rieur du c\u00f4t\u00e9 m\u00e2t ; l&#8217;\u00e9toile repr\u00e9sente Aruba et sa terre rouge et ses plages blanches, ses quatre points les quatre langues principales (papiamento, n\u00e9erlandais, espagnol, anglais) ainsi que les quatre points cardinaux, pour indiquer que ses habitants viennent du monde entier ; le bleu symbolise les eaux et le ciel des Cara\u00efbes ; les rayures repr\u00e9sentent les deux principales \u00ab\u00a0industries\u00a0\u00bb de l&#8217;\u00eele\u00a0: le flux de touristes vers les plages ensoleill\u00e9es et le flux de min\u00e9raux de la terre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le drapeau d&#8217;Aruba est bleu, avec deux bandes jaunes horizontales \u00e9troites sur la partie inf\u00e9rieure et une \u00e9toile rouge \u00e0 quatre branches soulign\u00e9e de blanc dans le coin sup\u00e9rieur du c\u00f4t\u00e9 m\u00e2t ; l&#8217;\u00e9toile repr\u00e9sente Aruba et sa terre rouge et ses plages blanches, ses quatre points les quatre langues p<\/p>\n","protected":false},"author":1,"featured_media":3521,"template":"","categoria_ficha":[46],"class_list":["post-279","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-d-aruba"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":4,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/279\/revisions"}],"predecessor-version":[{"id":19189,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/279\/revisions\/19189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/3521"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=279"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}