{"id":27232,"date":"2022-12-11T00:29:46","date_gmt":"2022-12-11T00:29:46","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=27232"},"modified":"2023-03-24T12:46:27","modified_gmt":"2023-03-24T12:46:27","slug":"carte-de-laval","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-de-laval\/","title":{"rendered":"Carte de Laval"},"content":{"rendered":"<p>Carte de Laval, une ville canadienne du Qu\u00e9bec de la banlieue de Montr\u00e9al. Elle constitue \u00e9galement l&#8217;une des dix-sept r\u00e9gions administratives de cette province, en plus de poss\u00e9der les comp\u00e9tences attribu\u00e9es aux municipalit\u00e9s r\u00e9gionales de comt\u00e9 (MRC). Avec sa population estim\u00e9e \u00e0 437 413 habitants en 2017, Laval est la troisi\u00e8me ville la plus peupl\u00e9e au Qu\u00e9bec, derri\u00e8re Montr\u00e9al et Qu\u00e9bec, ainsi que la treizi\u00e8me au Canada. La superficie de la ville est de 246,8 km\u00b2.<\/p>\n<figure id=\"attachment_27863\" aria-describedby=\"caption-attachment-27863\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/27232\/Carte-du-centre-ville-de-Laval-Quebec.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-27863\" title=\"Carte du centre-ville de Laval, Qu\u00e9bec.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/27232\/Carte-du-centre-ville-de-Laval-Quebec-300x242.jpg\" alt=\"Carte du centre-ville de Laval, Qu\u00e9bec.\" width=\"360\" height=\"290\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/27232\/Carte-du-centre-ville-de-Laval-Quebec-300x242.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/27232\/Carte-du-centre-ville-de-Laval-Quebec-1024x826.jpg 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/27232\/Carte-du-centre-ville-de-Laval-Quebec-768x619.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/27232\/Carte-du-centre-ville-de-Laval-Quebec-1536x1239.jpg 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/27232\/Carte-du-centre-ville-de-Laval-Quebec.jpg 1575w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-27863\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte du centre-ville de Laval, Qu\u00e9bec.<\/label><\/figcaption><\/figure>\n<p>Si la majorit\u00e9 du territoire de la ville est constitu\u00e9e de l&#8217;\u00eele J\u00e9sus, Laval comprend \u00e9galement une multitude de petites \u00eeles en son pourtour, qui font partie de l&#8217;archipel d&#8217;Hochelaga.<\/p>\n<p><strong>G\u00e9ographie<\/strong><\/p>\n<p>Sont repartis sur le territoire de Laval, en ordre d&#8217;importance\u00a0: les surfaces artificielles (56,9\u00a0%), les for\u00eats (16,6\u00a0%), les terres agricoles (16,4\u00a0%), les eaux (7,7\u00a0%) et finalement les milieux humides (2,4\u00a0%).<\/p>\n<p><strong>Situation<\/strong><\/p>\n<p>\u00c0 la fois ville et r\u00e9gion, Laval couvre l&#8217;enti\u00e8ret\u00e9 de l&#8217;\u00eele J\u00e9sus, imm\u00e9diatement au nord de l&#8217;\u00eele de Montr\u00e9al, au c\u0153ur de l&#8217;archipel d&#8217;Hochelaga. Avec Montr\u00e9al, la m\u00e9tropole du Qu\u00e9bec, Laval est le c\u0153ur de la Communaut\u00e9 m\u00e9tropolitaine de Montr\u00e9al, l&#8217;une des plus grandes agglom\u00e9rations urbaines du Canada.<\/p>\n<p>Sa superficie s&#8217;\u00e9tend sur 267 km\u00b2, dont 246 km\u00b2 qui sont terrestres, soit exactement 0,02 % du territoire qu\u00e9b\u00e9cois. Malgr\u00e9 sa tr\u00e8s faible superficie, Laval poss\u00e8de tout de m\u00eame le statut de \u00ab r\u00e9gion administrative \u00bb depuis 1987. Elle est de loin la plus petite r\u00e9gion : elle est 3 200 fois moins vaste que le Nord-du-Qu\u00e9bec, la plus grande. En raison de sa proximit\u00e9 imm\u00e9diate avec Montr\u00e9al, elle est en processus important d&#8217;\u00e9talement urbain depuis le milieu du XXe si\u00e8cle, la majorit\u00e9 de son territoire \u00e9tant d\u00e9sormais urbanis\u00e9.<\/p>\n<p><strong>Relief<\/strong><\/p>\n<p>Situ\u00e9 au milieu des basses-terres du Saint-Laurent, l&#8217;\u00eele poss\u00e8de un relief tr\u00e8s plat. Son altitude varie entre 4 m\u00e8tres (rivi\u00e8re des Prairies) et 65 m\u00e8tres (mont Laval). L&#8217;altitude est d&#8217;\u00e0 peine une dizaine de m\u00e8tres dans le quartier de Saint-Fran\u00e7ois, dans le secteur de la pointe est de l&#8217;\u00eele.<\/p>\n<p><strong>Hydrographie<\/strong><\/p>\n<p>L&#8217;\u00eele de Laval est form\u00e9e par deux rivi\u00e8res se rejoignant \u00e0 ses extr\u00e9mit\u00e9s\u00a0: la rivi\u00e8re des Mille \u00celes (au nord) et la rivi\u00e8re des Prairies (au sud). On retrouve \u00e0 l\u2019int\u00e9rieur de l&#8217;\u00eele pr\u00e8s de 70 km de ruisseaux permanents qui sillonnent le territoire. Les principaux sont les ruisseaux La Pini\u00e8re, Champagne, Papineau-Lavoie et Gascon. L&#8217;\u00eele ne poss\u00e8de aucun lac ou plan d&#8217;eau notable.<\/p>\n<p><strong>\u00c9conomie<\/strong><\/p>\n<p>Laval poss\u00e8de une \u00e9conomie surtout centr\u00e9e sur les secteurs de la haute technologie, des services, du commerce et de la sant\u00e9. On y retrouve ainsi plusieurs laboratoires pharmaceutiques, de nombreux commerces de d\u00e9tail, des carri\u00e8res de minerais et un secteur agricole vigoureux.<\/p>\n<p>Depuis quelques ann\u00e9es, Laval d\u00e9ploie beaucoup d&#8217;efforts\u00a0pour red\u00e9finir un territoire marqu\u00e9 par la s\u00e9paration des usages et un certain morcellement \u00e0 cause de son r\u00e9seau routier. Son centre-ville, caract\u00e9ris\u00e9 par une faible densit\u00e9, est actuellement mal d\u00e9fini mais fait l\u2019objet d\u2019un vaste plan de consolidation et de revitalisation. En 2020, la Place Bell, sa place publique et d\u2019autres \u00e9quipements culturels et sportifs se seront ajout\u00e9s au Centropolis et aux autres grands centres commerciaux, pour former un centre-ville mixte et moderne.<\/p>\n<p>La soci\u00e9t\u00e9 de d\u00e9veloppement \u00e9conomique Laval Technopole soutient six\u00a0axes de d\u00e9veloppement\u00a0: la Cit\u00e9 de la biotech, le p\u00f4le industriel, l&#8217;agrop\u00f4le,\u00a0le e-p\u00f4le, le p\u00f4le r\u00e9cr\u00e9otourisme et le p\u00f4le entreprises de services et si\u00e8ges sociaux. La r\u00e9ussite de ces p\u00f4les r\u00e9sulte des liens \u00e9troits entre les centres de recherche, les universit\u00e9s, les entreprises et les services publics.<\/p>\n<p>En d\u00e9cembre 2013, 12 021 entreprises \u00e9taient \u00e9tablies \u00e0 Laval et employaient 140 000 personnes. Seulement 40 % des Lavallois travaillent \u00e0 Laval.<\/p>\n<p><strong>Transports<\/strong><\/p>\n<p>Laval est desservie par plusieurs autoroutes et routes provinciales, le r\u00e9seau d\u2019autobus de la Soci\u00e9t\u00e9 de transport de Laval, trois stations de m\u00e9tro et des trains de banlieue.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laval est une ville canadienne du Qu\u00e9bec de la banlieue de Montr\u00e9al. Elle constitue \u00e9galement l&#8217;une des dix-sept r\u00e9gions administratives de cette province &#8230;<\/p>\n","protected":false},"author":1,"featured_media":27862,"template":"","categoria_ficha":[1923],"class_list":["post-27232","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-laval-quebec"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/27232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":9,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/27232\/revisions"}],"predecessor-version":[{"id":35934,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/27232\/revisions\/35934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/27862"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=27232"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=27232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}