{"id":26007,"date":"2022-11-20T13:08:14","date_gmt":"2022-11-20T13:08:14","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=26007"},"modified":"2023-03-24T15:56:26","modified_gmt":"2023-03-24T15:56:26","slug":"carte-de-la-mrc-de-kamouraska","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-de-la-mrc-de-kamouraska\/","title":{"rendered":"Carte de la MRC de Kamouraska"},"content":{"rendered":"<p style=\"text-align: center;\"><label style=\"font-size: 15px;\">Carte de la municipalit\u00e9 r\u00e9gionale de comt\u00e9 (MRC) de Kamouraska.<\/label><\/p>\n<p>Le Kamouraska est une municipalit\u00e9 r\u00e9gionale de comt\u00e9 (MRC) dans C\u00f4te-du-Sud de la r\u00e9gion administrative du Bas-Saint-Laurent, dans la province de Qu\u00e9bec, cr\u00e9\u00e9e le 1er janvier 1982. Son chef-lieu est la ville de Saint-Pascal. Elle est compos\u00e9e de 17 municipalit\u00e9s, soit 2 villes, 8 municipalit\u00e9s, 7 paroisses et 2 territoires non organis\u00e9s.<\/p>\n<figure id=\"attachment_26064\" aria-describedby=\"caption-attachment-26064\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-de-Saint-Pascal.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-26064\" title=\"Carte de Saint-Pascal.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-de-Saint-Pascal-300x232.jpg\" alt=\"Carte de Saint-Pascal.\" width=\"360\" height=\"278\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-de-Saint-Pascal-300x232.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-de-Saint-Pascal-1024x791.jpg 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-de-Saint-Pascal-768x593.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-de-Saint-Pascal-1536x1187.jpg 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-de-Saint-Pascal-2048x1583.jpg 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-de-Saint-Pascal-1600x1236.jpg 1600w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-26064\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte de Saint-Pascal, chef-lieu de la municipalit\u00e9 r\u00e9gionale de comt\u00e9 (MRC) de Kamouraska.<\/label><\/figcaption><\/figure>\n<p><strong>Portrait g\u00e9ophysique<\/strong><\/p>\n<p>La municipalit\u00e9 r\u00e9gionale de comt\u00e9 de Kamouraska s\u2019\u00e9tend sur une section longue de 60 km de la rive sud de l\u2019estuaire du fleuve Saint-Laurent, \u00e0 \u00e9quidistance des agglom\u00e9rations de Qu\u00e9bec et de Rimouski. Le territoire de la MRC se situe \u00e0 la limite occidentale du Bas-Saint-Laurent, r\u00e9gion dont il fait administrativement partie. Malgr\u00e9 cette appartenance bas-laurentienne, la MRC s\u2019av\u00e8re toutefois fr\u00e9quemment associ\u00e9e \u00e0 la C\u00f4te-du-Sud, sous-r\u00e9gion qui comprend plusieurs MRC voisines de la r\u00e9gion Chaudi\u00e8re-Appalaches.<\/p>\n<p>La superficie approximative du territoire est de 2 256 kilom\u00e8tres carr\u00e9s. Les \u00eeles les plus rapproch\u00e9es du littoral, soit les archipels des P\u00e8lerins et de Kamouraska, ainsi que l\u2019\u00eele aux Li\u00e8vres font \u00e9galement partie de la MRC. Les 21 500 citoyens kamouraskois se concentrent par contre sur une partie r\u00e9duite de ce vaste espace, soit au sein du territoire municipalis\u00e9 confin\u00e9 presque exclusivement dans la moiti\u00e9 nord-ouest du territoire. Le reste de la MRC, qui comprend deux territoires non-organis\u00e9s auxquels s\u2019ajoute une partie de la municipalit\u00e9 de Mont-Carmel, demeure pratiquement inhabit\u00e9. Dix-sept municipalit\u00e9s se partagent donc l\u2019\u00e9coum\u00e8ne. Un peu plus de la moiti\u00e9 du territoire (51,9\u00a0%) est sous gestion priv\u00e9e et poss\u00e9d\u00e9e majoritairement par de petits propri\u00e9taires; le reste (48,1\u00a0%), sous gestion publique, est compos\u00e9 en grande partie de for\u00eats du domaine public.<\/p>\n<figure id=\"attachment_27611\" aria-describedby=\"caption-attachment-27611\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-touristique-du-secteur-de-Kamouraska.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-27611\" title=\"Carte touristique du secteur de Kamouraska.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-touristique-du-secteur-de-Kamouraska-300x244.jpg\" alt=\"Carte touristique du secteur de Kamouraska.\" width=\"360\" height=\"293\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-touristique-du-secteur-de-Kamouraska-300x244.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-touristique-du-secteur-de-Kamouraska-1024x833.jpg 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-touristique-du-secteur-de-Kamouraska-768x625.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-touristique-du-secteur-de-Kamouraska-1536x1250.jpg 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/26007\/Carte-touristique-du-secteur-de-Kamouraska.jpg 1557w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-27611\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte touristique du secteur de Kamouraska.<\/label><\/figcaption><\/figure>\n<p><strong>Portrait \u00e9conomique<\/strong><\/p>\n<p>La base \u00e9conomique de la MRC est ax\u00e9e presque essentiellement sur une activit\u00e9-ressource: l\u2019agriculture. En y ajoutant la p\u00eache, l\u2019exploitation de la ressource ligneuse et l\u2019extraction de la tourbe, on s\u2019aper\u00e7oit rapidement que les activit\u00e9s primaires ont une grande importance dans le Kamouraska. Ce secteur repr\u00e9sente 13,8\u00a0% des emplois comparativement \u00e0 10,4\u00a0% pour le Bas-Saint-Laurent dans son ensemble et \u00e0 3,7\u00a0% pour tout le Qu\u00e9bec.<\/p>\n<p>Le secteur manufacturier, avec 24,0\u00a0% des effectifs, occupe quant \u00e0 lui une place comparable \u00e0 celle pr\u00e9sente \u00e0 l\u2019\u00e9chelle provinciale (22,0\u00a0%) et une situation sup\u00e9rieure \u00e0 celle constat\u00e9e \u00e0 l\u2019\u00e9chelle r\u00e9gionale (18,0\u00a0%). Le secteur sous-repr\u00e9sent\u00e9 s\u2019av\u00e8re donc le tertiaire en ne regroupant que 62,2\u00a0% des emplois. Il s\u2019agit d\u2019une repr\u00e9sentation nettement inf\u00e9rieure \u00e0 celles du Bas-Saint-Laurent (71,6\u00a0%) et du Qu\u00e9bec (74,3\u00a0%).<\/p>\n<p>\u00c0 l\u2019\u00e9chelle locale, on remarque une certaine sp\u00e9cialisation en termes de cat\u00e9gories d\u2019emplois. Les municipalit\u00e9s de la plaine littorale font des activit\u00e9s primaires la pierre angulaire de leur \u00e9conomie, les municipalit\u00e9s du piedmont sont davantage orient\u00e9es vers les activit\u00e9s de commerce et de services. Enfin, les communaut\u00e9s du plateau sont particuli\u00e8rement sp\u00e9cialis\u00e9es dans les activit\u00e9s de transformation, laissant une tr\u00e8s mince place au secteur tertiaire.<\/p>\n<p><strong>Routes d&#8217;acc\u00e8s de la MRC de Kamouraska<\/strong><\/p>\n<p>Routes num\u00e9rot\u00e9es qui traversent la municipalit\u00e9 r\u00e9gionale de comt\u00e9 (MRC), y compris les routes externes qui commencent ou se terminent \u00e0 la fronti\u00e8re de la MRC\u00a0:<\/p>\n<p>Autoroutes<\/p>\n<ul>\n<li>A-20<\/li>\n<\/ul>\n<p>Routes principales<\/p>\n<ul>\n<li>Route 132<\/li>\n<\/ul>\n<p>Routes secondaires<\/p>\n<ul>\n<li>Route 230<\/li>\n<li>Route 287<\/li>\n<li>Route 289<\/li>\n<\/ul>\n<p><strong>Municipalit\u00e9s<\/strong><\/p>\n<div class=\"boxscrl\">\n<table width=\"441\">\n<tbody>\n<tr>\n<td rowspan=\"2\" width=\"211\">Nom<\/td>\n<td rowspan=\"2\" width=\"85\">Type<\/td>\n<td width=\"75\">Population<\/td>\n<td width=\"70\">Superficie<\/td>\n<\/tr>\n<tr>\n<td>2016<\/td>\n<td width=\"70\">(km<sup>2<\/sup>)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"4\" width=\"441\">Municipalit\u00e9s locales<\/td>\n<\/tr>\n<tr>\n<td>Kamouraska<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">616<\/td>\n<td width=\"70\">43,86<\/td>\n<\/tr>\n<tr>\n<td>La Pocati\u00e8re<\/td>\n<td width=\"85\">Ville<\/td>\n<td width=\"75\">4\u00a0120<\/td>\n<td width=\"70\">21,63<\/td>\n<\/tr>\n<tr>\n<td>Mont-Carmel<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">1\u00a0127<\/td>\n<td width=\"70\">429,03<\/td>\n<\/tr>\n<tr>\n<td>Rivi\u00e8re-Ouelle<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">970<\/td>\n<td width=\"70\">57,78<\/td>\n<\/tr>\n<tr>\n<td>Saint-Alexandre-de-Kamouraska<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">2\u00a0109<\/td>\n<td width=\"70\">111,31<\/td>\n<\/tr>\n<tr>\n<td>Saint-Andr\u00e9-de-Kamouraska<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">658<\/td>\n<td width=\"70\">71,65<\/td>\n<\/tr>\n<tr>\n<td>Sainte-Anne-de-la-Pocati\u00e8re<\/td>\n<td width=\"85\">Paroisse<\/td>\n<td width=\"75\">1\u00a0636<\/td>\n<td width=\"70\">54,91<\/td>\n<\/tr>\n<tr>\n<td>Saint-Bruno-de-Kamouraska<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">541<\/td>\n<td width=\"70\">188,96<\/td>\n<\/tr>\n<tr>\n<td>Saint-Denis-De La Bouteillerie<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">517<\/td>\n<td width=\"70\">33,64<\/td>\n<\/tr>\n<tr>\n<td>Saint-Gabriel-Lalemant<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">716<\/td>\n<td width=\"70\">78,05<\/td>\n<\/tr>\n<tr>\n<td>Saint-Germain-de-Kamouraska<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">286<\/td>\n<td width=\"70\">28,60<\/td>\n<\/tr>\n<tr>\n<td>Sainte-H\u00e9l\u00e8ne-de-Kamouraska<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">918<\/td>\n<td width=\"70\">60,56<\/td>\n<\/tr>\n<tr>\n<td>Saint-Joseph-de-Kamouraska<\/td>\n<td width=\"85\">Paroisse<\/td>\n<td width=\"75\">391<\/td>\n<td width=\"70\">85,58<\/td>\n<\/tr>\n<tr>\n<td>Saint-On\u00e9sime-d&#8217;Ixworth<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">560<\/td>\n<td width=\"70\">102,89<\/td>\n<\/tr>\n<tr>\n<td>Saint-Pac\u00f4me<\/td>\n<td width=\"85\">Municipalit\u00e9<\/td>\n<td width=\"75\">1\u00a0598<\/td>\n<td width=\"70\">29,15<\/td>\n<\/tr>\n<tr>\n<td>Saint-Pascal<\/td>\n<td width=\"85\">Ville<\/td>\n<td width=\"75\">3\u00a0468<\/td>\n<td width=\"70\">59,69<\/td>\n<\/tr>\n<tr>\n<td>Saint-Philippe-de-N\u00e9ri<\/td>\n<td width=\"85\">Paroisse<\/td>\n<td width=\"75\">832<\/td>\n<td width=\"70\">32,68<\/td>\n<\/tr>\n<tr>\n<td colspan=\"4\" width=\"441\">Territoires non organis\u00e9s<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Petit-Lac-Sainte-Anne<\/td>\n<td width=\"75\">0<\/td>\n<td width=\"70\">186,61<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Picard<\/td>\n<td width=\"75\">10<\/td>\n<td width=\"70\">596,16<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" width=\"296\">Total<\/td>\n<td width=\"75\">21\u00a0073<\/td>\n<td width=\"70\">2\u00a0244,73<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le Kamouraska est une municipalit\u00e9 r\u00e9gionale de comt\u00e9 (MRC) dans C\u00f4te-du-Sud de la r\u00e9gion administrative du Bas-Saint-Laurent, dans la province de Qu\u00e9bec, cr\u00e9\u00e9e<\/p>\n","protected":false},"author":1,"featured_media":26152,"template":"","categoria_ficha":[1912],"class_list":["post-26007","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-du-bas-saint-laurent"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/26007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/26007\/revisions"}],"predecessor-version":[{"id":36245,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/26007\/revisions\/36245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/26152"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=26007"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=26007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}