{"id":23636,"date":"2022-09-05T16:05:31","date_gmt":"2022-09-05T16:05:31","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=23636"},"modified":"2022-09-05T16:06:55","modified_gmt":"2022-09-05T16:06:55","slug":"carte-de-marunouchi-tokyo","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-de-marunouchi-tokyo\/","title":{"rendered":"Carte de Marunouchi, Tokyo"},"content":{"rendered":"<p style=\"text-align: center;\"><label style=\"font-size: 15px;\">Carte de Marunouchi, Tokyo.<\/label><\/p>\n<p>Marunouchi est un quartier commercial de Tokyo situ\u00e9 dans l&#8217;arrondissement de Chiyoda entre la gare de Tokyo et le palais imp\u00e9rial. Marunouchi signifie \u00ab \u00e0 l&#8217;int\u00e9rieur du cercle \u00bb, en r\u00e9f\u00e9rence \u00e0 sa localisation \u00e0 l&#8217;int\u00e9rieur des douves du palais imp\u00e9rial. Le quartier est le centre financier du Japon, les trois plus grosses banques du pays y ont leur quartier g\u00e9n\u00e9ral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marunouchi est un quartier commercial de Tokyo situ\u00e9 dans l&#8217;arrondissement de Chiyoda entre la gare de Tokyo et le palais imp\u00e9rial. Marunouchi signifie \u00ab \u00e0 l&#8230;<\/p>\n","protected":false},"author":1,"featured_media":23637,"template":"","categoria_ficha":[409],"class_list":["post-23636","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-tokyo"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/23636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/23636\/revisions"}],"predecessor-version":[{"id":23639,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/23636\/revisions\/23639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/23637"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=23636"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=23636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}