{"id":231,"date":"2022-02-04T00:09:38","date_gmt":"2022-02-04T00:09:38","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=231"},"modified":"2023-02-01T19:07:47","modified_gmt":"2023-02-01T19:07:47","slug":"villes-du-nord-ouest-de-l-europe-vues-de-nuit-depuis-l-espace","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/villes-du-nord-ouest-de-l-europe-vues-de-nuit-depuis-l-espace\/","title":{"rendered":"Villes du nord-ouest de l&#8217;Europe vues de nuit depuis l&#8217;espace"},"content":{"rendered":"<p>Plusieurs des plus anciennes <strong>villes du nord-ouest de l&#8217;Europe<\/strong> sont mises en \u00e9vidence sur cette photo d&#8217;astronaute du 10 ao\u00fbt 2011. Alors que le paysage est parsem\u00e9 de grappes de lumi\u00e8re provenant de zones urbaines individuelles, les zones m\u00e9tropolitaines de Londres (en bas \u00e0 gauche), Paris (centre), Bruxelles, et Amsterdam (en haut \u00e0 gauche) se distinguent par leurs grandes \u00abempreintes\u00bb lumineuses. La zone m\u00e9tropolitaine de Milan est \u00e9galement visible sur l&#8217;image en haut \u00e0 droite. Alors que chacune de ces villes est, ou a \u00e9t\u00e9, la capitale d&#8217;un royaume, d&#8217;une r\u00e9publique ou d&#8217;un empire \u2013 Paris et Londres ont \u00e9t\u00e9 les trois \u2013 Bruxelles est \u00e9galement la capitale de l&#8217;Union europ\u00e9enne. Pour donner une id\u00e9e de l&#8217;\u00e9chelle, les centres des m\u00e9tropoles de Londres et de Paris sont distants d&#8217;environ 340 km. L&#8217;image est \u00e9galement oblique faisant appara\u00eetre la distance entre Paris et Milan (640 km) inf\u00e9rieure \u00e0 celle de Paris \u00e0 Londres. Contrairement \u00e0 la surface terrestre d\u00e9finie par les lumi\u00e8res de la ville, la Manche pr\u00e9sente un aspect sombre uniforme. De m\u00eame, les Alpes proches de Milan sont \u00e9galement largement d\u00e9pourvues de lumi\u00e8res. Alors qu&#8217;une grande partie de l&#8217;atmosph\u00e8re \u00e9tait claire au moment o\u00f9 l&#8217;image a \u00e9t\u00e9 prise, les lumi\u00e8res de Bruxelles sont tamis\u00e9es par une fine couverture nuageuse. Image satellite des \u201cvilles du nord-ouest de l&#8217;Europe vues de nuit depuis l&#8217;espace\u201d gracieuset\u00e9 de la NASA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plusieurs des plus anciennes villes du nord-ouest de l&#8217;Europe sont mises en \u00e9vidence sur cette photo d&#8217;astronaute du 10 ao\u00fbt 2011. Alors que le paysage est parsem\u00e9 de grappes de lumi\u00e8re provenant de zones urbaines individuelles, les zones m\u00e9tropolitaines de Londres (en bas \u00e0 gauche), Paris (centre),<\/p>\n","protected":false},"author":1,"featured_media":4155,"template":"","categoria_ficha":[41],"class_list":["post-231","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-de-l-europe"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":7,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/231\/revisions"}],"predecessor-version":[{"id":33309,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/231\/revisions\/33309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/4155"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=231"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}