{"id":17938,"date":"2022-07-26T17:16:50","date_gmt":"2022-07-26T17:16:50","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=17938"},"modified":"2022-08-20T22:07:09","modified_gmt":"2022-08-20T22:07:09","slug":"cartes-historiques-du-caucase","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/cartes-historiques-du-caucase\/","title":{"rendered":"Cartes historiques du Caucase"},"content":{"rendered":"<p style=\"text-align: center;\"><label style=\"font-size: 15px;\">L&#8217;Arm\u00e9nie, la M\u00e9sopotamie, la Babylonie et l&#8217;Assyrie avec les r\u00e9gions adjacentes, Karl von Spruner, carte publi\u00e9e par W. Alt sc. Gothae: Justhus Perthes. Spruner-Menke atlas antiquus. (1865).<\/label><\/p>\n<p>L&#8217;histoire de la r\u00e9gion du Caucase peut \u00eatre divis\u00e9e g\u00e9ographiquement en histoire du Caucase du Nord (Ciscaucasie), historiquement dans la sph\u00e8re d&#8217;influence de la Scythie et du sud de la Russie (Europe de l&#8217;Est), et celle du Caucase du Sud (Transcaucasie ; Albanie du Caucase, G\u00e9orgie, Arm\u00e9nie, Azerba\u00efdjan) dans la sph\u00e8re d&#8217;influence de la Perse, de l&#8217;Anatolie et (pour une tr\u00e8s courte p\u00e9riode) de l&#8217;Assyrie.<\/p>\n<figure id=\"attachment_17940\" aria-describedby=\"caption-attachment-17940\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Le-Royaume-d-Armenie-dans-sa-plus-grande-etendue-sous-Tigrane-le-Grand-vers-80-AEC.png\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-17940\" title=\"Le Royaume d'Arm\u00e9nie dans sa plus grande \u00e9tendue sous Tigrane II vers 80 AEC.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Le-Royaume-d-Armenie-dans-sa-plus-grande-etendue-sous-Tigrane-le-Grand-vers-80-AEC-300x170.png\" alt=\"Le Royaume d'Arm\u00e9nie dans sa plus grande \u00e9tendue sous Tigrane II vers 80 AEC.\" width=\"360\" height=\"204\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Le-Royaume-d-Armenie-dans-sa-plus-grande-etendue-sous-Tigrane-le-Grand-vers-80-AEC-300x170.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Le-Royaume-d-Armenie-dans-sa-plus-grande-etendue-sous-Tigrane-le-Grand-vers-80-AEC-1024x580.png 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Le-Royaume-d-Armenie-dans-sa-plus-grande-etendue-sous-Tigrane-le-Grand-vers-80-AEC-768x435.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Le-Royaume-d-Armenie-dans-sa-plus-grande-etendue-sous-Tigrane-le-Grand-vers-80-AEC.png 1500w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-17940\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Le Royaume d&#8217;Arm\u00e9nie dans sa plus grande \u00e9tendue sous Tigrane II vers 80 AEC.<\/label><\/figcaption><\/figure>\n<p>Tout au long de l&#8217;histoire, le Caucase du Sud et certaines parties du Caucase du Nord sont pass\u00e9s sous le contr\u00f4le de divers empires, notamment l&#8217;empire ach\u00e9m\u00e9nide, n\u00e9o-assyrien, parthe, romain, sassanide, byzantin, mongol, ottoman et iranien successif (S\u00e9f\u00e9vide, Afcharide, Kadjar). En 1813 et 1828, respectivement par le trait\u00e9 de Golestan et le trait\u00e9 de Turkmantcha\u00ef, la dynastie Kadjar a officiellement c\u00e9d\u00e9 ses territoires dans le Caucase dans ce qui est aujourd&#8217;hui le Daghestan, la G\u00e9orgie orientale, l&#8217;Azerba\u00efdjan et l&#8217;Arm\u00e9nie \u00e0 l&#8217;Empire russe. La Russie a conquis et annex\u00e9 le reste du Caucase du Nord au cours du XIXe si\u00e8cle lors des guerres du Caucase (1817-1864).<\/p>\n<figure id=\"attachment_17941\" aria-describedby=\"caption-attachment-17941\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-anciens-pays-du-Caucase-Armenie-Colchide-Iberie-et-Albanie.png\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-17941\" title=\"Carte des anciens pays du Caucase - Arm\u00e9nie, Colchide, Ib\u00e9rie et Albanie.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-anciens-pays-du-Caucase-Armenie-Colchide-Iberie-et-Albanie-300x213.png\" alt=\"Carte des anciens pays du Caucase - Arm\u00e9nie, Colchide, Ib\u00e9rie et Albanie.\" width=\"360\" height=\"256\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-anciens-pays-du-Caucase-Armenie-Colchide-Iberie-et-Albanie-300x213.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-anciens-pays-du-Caucase-Armenie-Colchide-Iberie-et-Albanie-1024x728.png 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-anciens-pays-du-Caucase-Armenie-Colchide-Iberie-et-Albanie-768x546.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-anciens-pays-du-Caucase-Armenie-Colchide-Iberie-et-Albanie-1536x1093.png 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-anciens-pays-du-Caucase-Armenie-Colchide-Iberie-et-Albanie-2048x1457.png 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-anciens-pays-du-Caucase-Armenie-Colchide-Iberie-et-Albanie-1600x1138.png 1600w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-17941\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte des anciens pays du Caucase &#8211; Arm\u00e9nie, Colchide, Ib\u00e9rie et Albanie.<\/label><\/figcaption><\/figure>\n<p>Le Caucase du Nord est devenu le th\u00e9\u00e2tre d&#8217;intenses combats pendant la Seconde Guerre mondiale. L&#8217;Allemagne nazie a tent\u00e9 de capturer la r\u00e9gion du Caucase de l&#8217;Union sovi\u00e9tique en 1942 par une attaque \u00e0 deux volets \u00e0 la fois vers la rive ouest de la Volga (destin\u00e9e \u00e0 s&#8217;emparer de la ville de Stalingrad) et au sud-est vers Bakou, un centre majeur de production de p\u00e9trole. Certaines parties du Caucase du Nord sont tomb\u00e9es sous l&#8217;occupation allemande, mais l&#8217;invasion de l&#8217;Axe a finalement \u00e9chou\u00e9 car elle n&#8217;a pas r\u00e9ussi \u00e0 atteindre l&#8217;un ou l&#8217;autre objectif, et les soldats sovi\u00e9tiques ont repouss\u00e9 les Allemands vers l&#8217;ouest apr\u00e8s la bataille de Stalingrad (1942-1943).<\/p>\n<p>Apr\u00e8s la dissolution de l&#8217;Union sovi\u00e9tique en 1991, l&#8217;Arm\u00e9nie, l&#8217;Azerba\u00efdjan et la G\u00e9orgie sont devenus des nations ind\u00e9pendantes. La r\u00e9gion du Caucase est devenue le cadre de conflits territoriaux \u00e0 l&#8217;\u00e8re post-sovi\u00e9tique, conduisant \u00e0 la cr\u00e9ation d&#8217;\u00c9tats non reconnus d&#8217;Artsakh, d&#8217;Abkhazie et d&#8217;Oss\u00e9tie du Sud.<\/p>\n<figure id=\"attachment_17943\" aria-describedby=\"caption-attachment-17943\" style=\"width: 400px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-de-la-region-du-Caucase-vers-1060-CE.png\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-17943\" title=\"Carte politique de la r\u00e9gion du Caucase vers 1060.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-de-la-region-du-Caucase-vers-1060-CE-300x233.png\" alt=\"Carte politique de la r\u00e9gion du Caucase vers 1060.\" width=\"400\" height=\"311\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-de-la-region-du-Caucase-vers-1060-CE-300x233.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-de-la-region-du-Caucase-vers-1060-CE-1024x796.png 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-de-la-region-du-Caucase-vers-1060-CE-768x597.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-de-la-region-du-Caucase-vers-1060-CE-1536x1194.png 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-de-la-region-du-Caucase-vers-1060-CE-2048x1592.png 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-de-la-region-du-Caucase-vers-1060-CE-1600x1244.png 1600w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><figcaption id=\"caption-attachment-17943\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte politique de la r\u00e9gion du Caucase vers 1060.<\/label><\/figcaption><\/figure>\n<figure id=\"attachment_17944\" aria-describedby=\"caption-attachment-17944\" style=\"width: 400px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-vers-1213-EC.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17944\" title=\"Carte de la r\u00e9gion du Caucase vers 1213 EC.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-vers-1213-EC-300x233.png\" alt=\"Carte de la r\u00e9gion du Caucase vers 1213 EC.\" width=\"400\" height=\"311\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-vers-1213-EC-300x233.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-vers-1213-EC-1024x796.png 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-vers-1213-EC-768x597.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-vers-1213-EC-1536x1194.png 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-vers-1213-EC-2048x1592.png 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-vers-1213-EC-1600x1244.png 1600w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><figcaption id=\"caption-attachment-17944\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte de la r\u00e9gion du Caucase vers 1213 EC.<\/label><\/figcaption><\/figure>\n<figure id=\"attachment_17946\" aria-describedby=\"caption-attachment-17946\" style=\"width: 400px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-1405.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17946\" title=\"Carte de la r\u00e9gion du Caucase 1405.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-1405-300x233.png\" alt=\"Carte de la r\u00e9gion du Caucase 1405.\" width=\"400\" height=\"311\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-1405-300x233.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-1405-1024x796.png 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-1405-768x597.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-1405-1536x1194.png 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-1405-2048x1592.png 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-de-la-region-du-Caucase-1405-1600x1244.png 1600w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><figcaption id=\"caption-attachment-17946\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte de la r\u00e9gion du Caucase 1405.<\/label><\/figcaption><\/figure>\n<figure id=\"attachment_17947\" aria-describedby=\"caption-attachment-17947\" style=\"width: 400px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Frontieres-dans-la-region-du-Caucase-en-1799.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17947\" title=\"Fronti\u00e8res dans la r\u00e9gion du Caucase en 1799.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Frontieres-dans-la-region-du-Caucase-en-1799-300x249.png\" alt=\"Fronti\u00e8res dans la r\u00e9gion du Caucase en 1799.\" width=\"400\" height=\"332\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Frontieres-dans-la-region-du-Caucase-en-1799-300x249.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Frontieres-dans-la-region-du-Caucase-en-1799-1024x850.png 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Frontieres-dans-la-region-du-Caucase-en-1799-768x637.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Frontieres-dans-la-region-du-Caucase-en-1799-1536x1275.png 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Frontieres-dans-la-region-du-Caucase-en-1799-2048x1700.png 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Frontieres-dans-la-region-du-Caucase-en-1799-1600x1328.png 1600w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><figcaption id=\"caption-attachment-17947\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Fronti\u00e8res dans la r\u00e9gion du Caucase en 1799.<\/label><\/figcaption><\/figure>\n<figure id=\"attachment_17949\" aria-describedby=\"caption-attachment-17949\" style=\"width: 400px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-Khanats-du-Caucase-et-de-l-avancee-russe-dans-le-Caucase-au-XIXeme-siecle.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17949\" title=\"Carte des Khanats du Caucase et de l'avanc\u00e9e russe dans le Caucase au XIX\u00e8me si\u00e8cle.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-Khanats-du-Caucase-et-de-l-avancee-russe-dans-le-Caucase-au-XIXeme-siecle-300x218.png\" alt=\"Carte des Khanats du Caucase et de l'avanc\u00e9e russe dans le Caucase au XIX\u00e8me si\u00e8cle.\" width=\"400\" height=\"291\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-Khanats-du-Caucase-et-de-l-avancee-russe-dans-le-Caucase-au-XIXeme-siecle-300x218.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-Khanats-du-Caucase-et-de-l-avancee-russe-dans-le-Caucase-au-XIXeme-siecle-1024x745.png 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-Khanats-du-Caucase-et-de-l-avancee-russe-dans-le-Caucase-au-XIXeme-siecle-768x559.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-Khanats-du-Caucase-et-de-l-avancee-russe-dans-le-Caucase-au-XIXeme-siecle-1536x1117.png 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-Khanats-du-Caucase-et-de-l-avancee-russe-dans-le-Caucase-au-XIXeme-siecle-2048x1490.png 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-des-Khanats-du-Caucase-et-de-l-avancee-russe-dans-le-Caucase-au-XIXeme-siecle-1600x1164.png 1600w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><figcaption id=\"caption-attachment-17949\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte des Khanats du Caucase et de l&#8217;avanc\u00e9e russe dans le Caucase au XIX\u00e8me si\u00e8cle.<\/label><\/figcaption><\/figure>\n<figure id=\"attachment_17954\" aria-describedby=\"caption-attachment-17954\" style=\"width: 400px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-du-Caucase-et-de-ses-environs-entre-1795-et-1801.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17954\" title=\"Carte politique du Caucase et de ses environs entre 1795 et 1801.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-du-Caucase-et-de-ses-environs-entre-1795-et-1801-300x165.png\" alt=\"Carte politique du Caucase et de ses environs entre 1795 et 1801.\" width=\"400\" height=\"220\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-du-Caucase-et-de-ses-environs-entre-1795-et-1801-300x165.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-du-Caucase-et-de-ses-environs-entre-1795-et-1801-1024x563.png 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-du-Caucase-et-de-ses-environs-entre-1795-et-1801-768x422.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-du-Caucase-et-de-ses-environs-entre-1795-et-1801-1536x845.png 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-du-Caucase-et-de-ses-environs-entre-1795-et-1801-2048x1126.png 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-politique-du-Caucase-et-de-ses-environs-entre-1795-et-1801-1600x880.png 1600w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><figcaption id=\"caption-attachment-17954\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte politique du Caucase et de ses environs entre 1795 et 1801.<\/label><\/figcaption><\/figure>\n<figure id=\"attachment_17956\" aria-describedby=\"caption-attachment-17956\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-administrative-du-Caucase-en-URSS-1957-1991.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17956\" title=\"Carte administrative du Caucase en URSS, 1957-1991.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-administrative-du-Caucase-en-URSS-1957-1991-300x253.png\" alt=\"Carte administrative du Caucase en URSS, 1957-1991.\" width=\"400\" height=\"337\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-administrative-du-Caucase-en-URSS-1957-1991-300x253.png 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-administrative-du-Caucase-en-URSS-1957-1991-1024x862.png 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-administrative-du-Caucase-en-URSS-1957-1991-768x647.png 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-administrative-du-Caucase-en-URSS-1957-1991-1536x1293.png 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-administrative-du-Caucase-en-URSS-1957-1991-2048x1725.png 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/17938\/Carte-administrative-du-Caucase-en-URSS-1957-1991-1600x1347.png 1600w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><figcaption id=\"caption-attachment-17956\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte administrative du Caucase en URSS, 1957-1991.<\/label><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Arm\u00e9nie, la M\u00e9sopotamie, la Babylonie et l&#8217;Assyrie avec les r\u00e9gions adjacentes, Karl von Spruner, carte publi\u00e9e par W. Alt sc. Gothae: Justhus Perthes. Spruner-Menke atlas antiquus. (1865). L&#8217;histoire de la r\u00e9gion du Caucase peut \u00eatre divis\u00e9e g\u00e9ographiquement en histoire du Caucase du Nord (Ciscaucasie), historiquement dans la sph\u00e8re d&#8217;influence de la Scythie et du sud [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17939,"template":"","categoria_ficha":[398],"class_list":["post-17938","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-du-caucase"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/17938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":11,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/17938\/revisions"}],"predecessor-version":[{"id":22690,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/17938\/revisions\/22690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/17939"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=17938"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=17938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}