{"id":1437,"date":"2022-02-04T00:20:49","date_gmt":"2022-02-04T00:20:49","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=1437"},"modified":"2022-08-08T16:12:46","modified_gmt":"2022-08-08T16:12:46","slug":"lac-kara-kul-dans-les-montagnes-du-pamir","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/lac-kara-kul-dans-les-montagnes-du-pamir\/","title":{"rendered":"Lac Kara-Kul dans les montagnes du Pamir"},"content":{"rendered":"<p>Au centre de cette sc\u00e8ne se trouve le <strong>lac de montagne Kara-Kul<\/strong>, situ\u00e9 dans l&#8217;est du Tadjikistan, haut dans la cha\u00eene de montagnes du Pamir pr\u00e8s de la fronti\u00e8re afghane. Le lac de 25 km de diam\u00e8tre se trouve \u00e0 une altitude d&#8217;environ 4 000 m au-dessus du niveau de la mer. Kara-Kul s&#8217;est form\u00e9 \u00e0 partir d&#8217;un impact de m\u00e9t\u00e9orite il y a environ 25 millions d&#8217;ann\u00e9es, laissant un crat\u00e8re d&#8217;un diam\u00e8tre de 45 km. Des \u00eeles form\u00e9es \u00e0 partir du soul\u00e8vement central peuvent \u00eatre vues dans les parties nord et sud du lac. Fait int\u00e9ressant, la structure d&#8217;impact de Kara-Kul est rest\u00e9e non identifi\u00e9e jusqu&#8217;\u00e0 ce qu&#8217;elle soit d\u00e9couverte gr\u00e2ce \u00e0 des \u00e9tudes d&#8217;images prises depuis l&#8217;espace. Image satellite du \u00ablac Kara-Kul dans les montagnes du Pamir\u00bb gracieuset\u00e9 de la NASA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au centre de cette sc\u00e8ne se trouve le lac de montagne Kara-Kul, situ\u00e9 dans l&#8217;est du Tadjikistan, haut dans la cha\u00eene de montagnes du Pamir pr\u00e8s de la fronti\u00e8re afghane. Le lac de 25 km de diam\u00e8tre se trouve \u00e0 une altitude d&#8217;environ 4 000 m au-dessus du niveau de la mer. Kara-Kul s&#8217;est form\u00e9 \u00e0 p<\/p>\n","protected":false},"author":1,"featured_media":6156,"template":"","categoria_ficha":[184],"class_list":["post-1437","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-du-tadjikistan"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/1437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":4,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/1437\/revisions"}],"predecessor-version":[{"id":19703,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/1437\/revisions\/19703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/6156"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=1437"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=1437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}