{"id":1383,"date":"2022-02-04T00:20:20","date_gmt":"2022-02-04T00:20:20","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=1383"},"modified":"2024-09-15T00:02:47","modified_gmt":"2024-09-15T00:02:47","slug":"carte-du-qatar","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-du-qatar\/","title":{"rendered":"Carte du Qatar"},"content":{"rendered":"<p><strong>Carte d\u00e9taill\u00e9e gratuite du Qatar <a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/1383\/Carte-du-Qatar.pdf\" target=\"_blank\" rel=\"noopener\">(format pdf)<\/a><\/strong>, officiellement l&#8217;\u00c9tat du Qatar, un pays situ\u00e9 en Asie occidentale, occupant la petite p\u00e9ninsule du Qatar sur la c\u00f4te nord-est de la p\u00e9ninsule arabique. Sa seule fronti\u00e8re terrestre est avec la monarchie voisine, l&#8217;Arabie saoudite au sud, le reste de son territoire \u00e9tant entour\u00e9 par le golfe Persique. Le golfe de Bahre\u00efn, une anse du golfe Persique, s\u00e9pare le Qatar du Bahre\u00efn voisin. Sa capitale est Doha, sa langue officielle l&#8217;arabe, et sa monnaie le riyal qatarien.<\/p>\n<figure id=\"attachment_50633\" aria-describedby=\"caption-attachment-50633\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/50632\/Carte-de-Doha.gif\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-50633\" title=\"Carte de Doha.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/50632\/Carte-de-Doha-300x282.gif\" alt=\"Carte de Doha.\" width=\"360\" height=\"339\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/50632\/Carte-de-Doha-300x282.gif 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/50632\/Carte-de-Doha-1024x963.gif 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/50632\/Carte-de-Doha-768x722.gif 768w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-50633\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Carte de Doha, capitale et plus grande ville du Qatar.<\/label><\/figcaption><\/figure>\n<ul>\n<li>Superficie totale du Qatar 11,586 km\u00b2<\/li>\n<li>En 2020 la population du Qatar \u00e9tait de 2,795,484<\/li>\n<li>La capitale et plus grande ville du pays est Doha<\/li>\n<\/ul>\n<p>Au d\u00e9but de 2017, la population totale du Qatar \u00e9tait de 2,6 millions: 313 000 citoyens qataris et 2,3 millions d&#8217;expatri\u00e9s. L&#8217;islam est la religion officielle du Qatar.<\/p>\n<p>En termes de revenu, le pays a le troisi\u00e8me PIB par habitant (PPA) le plus \u00e9lev\u00e9 au monde, et le sixi\u00e8me RNB par habitant (m\u00e9thode Atlas). Le Qatar est class\u00e9 par l&#8217;ONU comme un pays \u00e0 tr\u00e8s haut d\u00e9veloppement humain, ayant le troisi\u00e8me IDH le plus \u00e9lev\u00e9 dans le monde arabe apr\u00e8s les \u00c9mirats arabes unis et l&#8217;Arabie saoudite.<\/p>\n<p>Le Qatar est une \u00e9conomie \u00e0 revenu \u00e9lev\u00e9 selon la d\u00e9finition de la Banque mondiale, soutenue par les troisi\u00e8mes plus grandes r\u00e9serves de gaz naturel et de p\u00e9trole au monde. Le Qatar est le plus grand \u00e9metteur de gaz \u00e0 effet de serre au monde par habitant.<\/p>\n<figure id=\"attachment_50642\" aria-describedby=\"caption-attachment-50642\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/1383\/Image-satellite-du-Qatar-du-31-janvier-2003.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-50642\" title=\"Image satellite du Qatar du 31 janvier 2003.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/1383\/Image-satellite-du-Qatar-du-31-janvier-2003-242x300.jpg\" alt=\"Image satellite du Qatar du 31 janvier 2003.\" width=\"360\" height=\"446\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/1383\/Image-satellite-du-Qatar-du-31-janvier-2003-242x300.jpg 242w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/1383\/Image-satellite-du-Qatar-du-31-janvier-2003-827x1024.jpg 827w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/1383\/Image-satellite-du-Qatar-du-31-janvier-2003-768x951.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/1383\/Image-satellite-du-Qatar-du-31-janvier-2003-300x372.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/1383\/Image-satellite-du-Qatar-du-31-janvier-2003.jpg 1110w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-50642\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Image satellite du Qatar du 31 janvier 2003.<\/label><\/figcaption><\/figure>\n<p>Le Qatar est gouvern\u00e9 par la maison Al Thani depuis que Mohammed bin Thani a sign\u00e9 un trait\u00e9 avec les Britanniques en 1868 qui reconnaissait son statut distinct. Apr\u00e8s la domination ottomane, le Qatar est devenu un protectorat britannique au d\u00e9but du XX<sup>e<\/sup> si\u00e8cle jusqu&#8217;\u00e0 son ind\u00e9pendance en 1971.<\/p>\n<p>L&#8217;\u00e9mir h\u00e9r\u00e9ditaire du Qatar r\u00e8gne en autocrate (actuellement Tamim ben Hamad Al Thani) et d\u00e9tient tous les pouvoirs ex\u00e9cutif et l\u00e9gislatif, ainsi que le contr\u00f4le du syst\u00e8me judiciaire. Il nomme le Premier ministre et le cabinet. Les \u00e9lections ne sont ni libres ni \u00e9quitables et les droits politiques sont limit\u00e9s au Qatar.<\/p>\n<p>Au 21<sup>e<\/sup> si\u00e8cle, le Qatar a \u00e9merg\u00e9 comme une puissance importante dans le monde arabe gr\u00e2ce \u00e0 ses richesses en ressources, ainsi qu&#8217;\u00e0 son groupe m\u00e9diatique en expansion mondiale, Al Jazeera Media Network, et aurait soutenu financi\u00e8rement plusieurs groupes rebelles pendant le printemps arabe.<\/p>\n<p>Compte tenu de sa taille, le Qatar exerce une influence disproportionn\u00e9e dans le monde et a \u00e9t\u00e9 identifi\u00e9 comme une puissance moyenne. La Coupe du Monde de la FIFA 2022 a eu lieu au Qatar, ce qui en fait le premier pays musulman et arabe \u00e0 accueillir l&#8217;\u00e9v\u00e9nement. Les Jeux asiatiques de 2030 auront \u00e9galement lieu au Qatar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carte d\u00e9taill\u00e9e gratuite du Qatar (format pdf), officiellement l&#8217;\u00c9tat du Qatar, un pays situ\u00e9 en Asie occidentale, occupant la petite p\u00e9ninsule du Qatar &#8230;<\/p>\n","protected":false},"author":1,"featured_media":50579,"template":"","categoria_ficha":[178],"class_list":["post-1383","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-du-qatar"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/1383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":7,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/1383\/revisions"}],"predecessor-version":[{"id":50643,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/1383\/revisions\/50643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/50579"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=1383"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=1383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}