{"id":13087,"date":"2022-05-15T21:54:00","date_gmt":"2022-05-15T21:54:00","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=13087"},"modified":"2022-11-30T21:36:55","modified_gmt":"2022-11-30T21:36:55","slug":"les-arrondissements-du-departement-de-la-moselle","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/les-arrondissements-du-departement-de-la-moselle\/","title":{"rendered":"Les arrondissements du d\u00e9partement de la Moselle"},"content":{"rendered":"<p style=\"text-align: center;\"><label style=\"font-size: 15px;\">Carte des arrondissements du d\u00e9partement de la Moselle.<\/label><\/p>\n<p>Les arrondissements du d\u00e9partement de la Moselle sont des circonscriptions administratives, \u00e0 savoir des zones g\u00e9ographiques r\u00e9sultant d&#8217;un d\u00e9coupage du territoire d\u00e9partemental pour les besoins de la gestion administrative. Ces arrondissements sont des subdivisions interm\u00e9diaires entre les d\u00e9partements et les cantons, et sont rapidement assimil\u00e9s aux sous-pr\u00e9fectures. D\u00e9pourvues de personnalit\u00e9 morale, ils servent de cadre \u00e0 l&#8217;action de l&#8217;Etat dans le d\u00e9partement et deviennent, depuis la r\u00e9duction cantonale de 2015, des divisions supra-communales.<\/p>\n<p>Ces arrondissements sont g\u00e9n\u00e9ralement administr\u00e9s par un sous-pr\u00e9fet (sauf l&#8217;arrondissement dont le chef-lieu est \u00e9galement celui du d\u00e9partement, qui est administr\u00e9 par le secr\u00e9taire g\u00e9n\u00e9ral de pr\u00e9fecture).<\/p>\n<p>Les 5 arrondissements du d\u00e9partement de la Moselle au 29 mars 2017.<\/p>\n<div class=\"boxscrl\">\n<table width=\"737\">\n<tbody>\n<tr>\n<td width=\"41\">Code<\/td>\n<td rowspan=\"2\" width=\"300\">Arrondissement<\/td>\n<td rowspan=\"2\" width=\"100\">Chef-lieu<\/td>\n<td width=\"75\">Population<\/td>\n<td width=\"70\">Superficie<\/td>\n<td width=\"74\">Densit\u00e9<\/td>\n<td width=\"77\">Communes<\/td>\n<\/tr>\n<tr>\n<td width=\"41\">Insee<\/td>\n<td width=\"75\">2019<\/td>\n<td width=\"70\">(km<sup>2<\/sup>)<\/td>\n<td width=\"74\">(hab.\/km<sup>2<\/sup>)<\/td>\n<td width=\"77\">2022<\/td>\n<\/tr>\n<tr>\n<td width=\"41\">573<\/td>\n<td width=\"300\">Arrondissement de Forbach-Boulay-Moselle<\/td>\n<td width=\"100\">Forbach<\/td>\n<td width=\"75\">239\u00a0614<\/td>\n<td width=\"70\">1\u00a0283,3<\/td>\n<td width=\"74\">186,7<\/td>\n<td width=\"77\">169<\/td>\n<\/tr>\n<tr>\n<td width=\"41\">575<\/td>\n<td width=\"300\">Arrondissement de Sarrebourg-Ch\u00e2teau-Salins<\/td>\n<td width=\"100\">Sarrebourg<\/td>\n<td width=\"75\">91\u00a0535<\/td>\n<td width=\"70\">1\u00a0966,9<\/td>\n<td width=\"74\">46,5<\/td>\n<td width=\"77\">230<\/td>\n<\/tr>\n<tr>\n<td width=\"41\">576<\/td>\n<td width=\"300\">Arrondissement de Sarreguemines<\/td>\n<td width=\"100\">Sarreguemines<\/td>\n<td width=\"75\">97\u00a0488<\/td>\n<td width=\"70\">935,9<\/td>\n<td width=\"74\">104,2<\/td>\n<td width=\"77\">83<\/td>\n<\/tr>\n<tr>\n<td width=\"41\">577<\/td>\n<td width=\"300\">Arrondissement de Thionville<\/td>\n<td width=\"100\">Thionville<\/td>\n<td width=\"75\">269\u00a0974<\/td>\n<td width=\"70\">941,5<\/td>\n<td width=\"74\">286,7<\/td>\n<td width=\"77\">104<\/td>\n<\/tr>\n<tr>\n<td width=\"41\">579<\/td>\n<td width=\"300\">Arrondissement de Metz<\/td>\n<td width=\"100\">Metz<\/td>\n<td width=\"75\">347\u00a0932<\/td>\n<td width=\"70\">1\u00a0088,7<\/td>\n<td width=\"74\">319,6<\/td>\n<td width=\"77\">139<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Carte des arrondissements du d\u00e9partement de la Moselle. Les arrondissements du d\u00e9partement de la Moselle sont des circonscriptions administratives, \u00e0 savoir des zones g\u00e9ographiques r\u00e9sultant d&#8217;un d\u00e9coupage du territoire d\u00e9partemental pour les besoins de la gestion administrative. Ces arrondissements sont des subdivisions interm\u00e9diaires entre les d\u00e9partements et les cantons, et sont rapidement assimil\u00e9s aux sous-pr\u00e9fectures. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13088,"template":"","categoria_ficha":[1844],"class_list":["post-13087","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-du-departement-de-la-moselle"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/13087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":5,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/13087\/revisions"}],"predecessor-version":[{"id":26718,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/13087\/revisions\/26718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/13088"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=13087"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=13087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}