{"id":12018,"date":"2022-05-03T22:59:59","date_gmt":"2022-05-03T22:59:59","guid":{"rendered":"https:\/\/gifex.com\/fr\/?post_type=ficha&#038;p=12018"},"modified":"2024-11-08T15:58:56","modified_gmt":"2024-11-08T15:58:56","slug":"carte-de-la-haute-marne","status":"publish","type":"ficha","link":"https:\/\/gifex.com\/fr\/fichier\/carte-de-la-haute-marne\/","title":{"rendered":"Carte de la Haute-Marne"},"content":{"rendered":"<p>Carte de la Haute-Marne <a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/Carte-de-la-Haute-Marne.pdf\" target=\"_blank\" rel=\"noopener\">(format pdf)<\/a>, un d\u00e9partement formant la partie m\u00e9ridionale de la r\u00e9gion Grand Est (avec le Haut-Rhin), nomm\u00e9 d&#8217;apr\u00e8s la rivi\u00e8re Marne. L&#8217;Insee et La Poste lui attribuent le code 52.<\/p>\n<figure id=\"attachment_12020\" aria-describedby=\"caption-attachment-12020\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/Siege-de-la-prefecture-du-departement-de-la-Haute-Marne-a-Chaumont-2012.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-12020\" title=\"Si\u00e8ge de la pr\u00e9fecture du d\u00e9partement de la Haute-Marne \u00e0 Chaumont.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/Siege-de-la-prefecture-du-departement-de-la-Haute-Marne-a-Chaumont-2012-300x177.jpg\" alt=\"Si\u00e8ge de la pr\u00e9fecture du d\u00e9partement de la Haute-Marne \u00e0 Chaumont.\" width=\"360\" height=\"213\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/Siege-de-la-prefecture-du-departement-de-la-Haute-Marne-a-Chaumont-2012-300x177.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/Siege-de-la-prefecture-du-departement-de-la-Haute-Marne-a-Chaumont-2012-1024x605.jpg 1024w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/Siege-de-la-prefecture-du-departement-de-la-Haute-Marne-a-Chaumont-2012-768x454.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/Siege-de-la-prefecture-du-departement-de-la-Haute-Marne-a-Chaumont-2012-1536x908.jpg 1536w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/Siege-de-la-prefecture-du-departement-de-la-Haute-Marne-a-Chaumont-2012-2048x1210.jpg 2048w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/Siege-de-la-prefecture-du-departement-de-la-Haute-Marne-a-Chaumont-2012-1600x946.jpg 1600w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-12020\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">Si\u00e8ge de la pr\u00e9fecture du d\u00e9partement de la Haute-Marne \u00e0 Chaumont.<\/label><\/figcaption><\/figure>\n<ul>\n<li>Superficie totale de la Haute-Marne 6 211 km\u00b2<\/li>\n<li>En 2019 la population de la Haute-Marne \u00e9tait de 172 512<\/li>\n<li>Le Chef-lieu du d\u00e9partement est Chaumont<\/li>\n<li>Les principales communes de la Haute-Marne sont: Saint-Dizier, Chaumont, Langres et Nogent.<\/li>\n<\/ul>\n<p>Le d\u00e9partement de la Haute-Marne n&#8217;est pas un d\u00e9partement r\u00e9put\u00e9 mais ce territoire paisible a de nombreux lieux int\u00e9ressants \u00e0 pr\u00e9senter. En effet, le d\u00e9partement a \u00e9t\u00e9 l&#8217;un des plus puissants de l&#8217;histoire de France gr\u00e2ce \u00e0 l&#8217;\u00e9conomie m\u00e9tallurgique et a \u00e9t\u00e9 une terre d&#8217;affrontements tout au long de l&#8217;histoire.<\/p>\n<figure id=\"attachment_12022\" aria-describedby=\"caption-attachment-12022\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/La-Boisserie-Residence-du-general-de-Gaulle-a-Colombey-les-deux-eglises-2009.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-12022\" title=\"La Boisserie - R\u00e9sidence du g\u00e9n\u00e9ral de Gaulle \u00e0 Colombey-les-deux-\u00e9glises.\" src=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/La-Boisserie-Residence-du-general-de-Gaulle-a-Colombey-les-deux-eglises-2009-300x225.jpg\" alt=\"La Boisserie - R\u00e9sidence du g\u00e9n\u00e9ral de Gaulle \u00e0 Colombey-les-deux-\u00e9glises.\" width=\"360\" height=\"270\" srcset=\"https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/La-Boisserie-Residence-du-general-de-Gaulle-a-Colombey-les-deux-eglises-2009-300x225.jpg 300w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/La-Boisserie-Residence-du-general-de-Gaulle-a-Colombey-les-deux-eglises-2009-768x576.jpg 768w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/La-Boisserie-Residence-du-general-de-Gaulle-a-Colombey-les-deux-eglises-2009-800x600.jpg 800w, https:\/\/gifex.com\/fr\/wp-content\/uploads\/12018\/La-Boisserie-Residence-du-general-de-Gaulle-a-Colombey-les-deux-eglises-2009.jpg 1024w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-12022\" class=\"wp-caption-text\"><label style=\"font-size: 15px;\">La Boisserie &#8211; R\u00e9sidence du g\u00e9n\u00e9ral de Gaulle \u00e0 Colombey-les-deux-\u00e9glises.<\/label><\/figcaption><\/figure>\n<p>Ainsi, entre autres exemples, les guerres de religion fran\u00e7aises (de 1562 \u00e0 1598) d\u00e9butent avec le massacre de Vassy dans le nord du d\u00e9partement de la Haute-Marne. \u00c0 la suite de cet \u00e9v\u00e9nement, des conflits militaires ouverts \u00e0 travers le Royaume de France ont commenc\u00e9. L&#8217;\u00e9dit de Nantes est la cons\u00e9quence de cette p\u00e9riode.<\/p>\n<p>La bastide de Langres, c\u00e9l\u00e8bre pour Denis Diderot auteur de l&#8217;Encyclop\u00e9die, le ch\u00e2teau Renaissance de Joinville, le lac du Der-Chantecoq (l&#8217;un des plus grands lac artificiel d&#8217;Europe), le ch\u00e2teau de Cirey o\u00f9 Voltaire v\u00e9cut un temps avec \u00c9milie du Ch\u00e2telet et le village de Colombey-les-Deux-\u00c9glises o\u00f9 Charles De Gaulle a v\u00e9cu jusqu&#8217;\u00e0 sa mort sont autant d&#8217;attractions majeures.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carte de la Haute-Marne (format pdf), un d\u00e9partement formant la partie m\u00e9ridionale de la r\u00e9gion Grand Est (avec le Haut-Rhin), nomm\u00e9 d&#8217;apr\u00e8s la rivi\u00e8re Marne. <\/p>\n","protected":false},"author":1,"featured_media":53719,"template":"","categoria_ficha":[1839],"class_list":["post-12018","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","categoria_ficha-cartes-du-departement-de-la-haute-marne"],"acf":[],"_links":{"self":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/12018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"author":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/12018\/revisions"}],"predecessor-version":[{"id":53720,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/ficha\/12018\/revisions\/53720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media\/53719"}],"wp:attachment":[{"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/media?parent=12018"}],"wp:term":[{"taxonomy":"categoria_ficha","embeddable":true,"href":"https:\/\/gifex.com\/fr\/wp-json\/wp\/v2\/categoria_ficha?post=12018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}